{"id":127956,"date":"2026-05-04T09:13:48","date_gmt":"2026-05-04T12:13:48","guid":{"rendered":"https:\/\/monitoramento.spmj.com.br\/noticias\/?p=127956"},"modified":"2026-05-04T09:13:48","modified_gmt":"2026-05-04T12:13:48","slug":"multiplan-mult3-fecha-1o-tri-com-lucro-de-r-316-mi-alta-anual-de-35","status":"publish","type":"post","link":"https:\/\/monitoramento.spmj.com.br\/noticias\/2026\/05\/04\/multiplan-mult3-fecha-1o-tri-com-lucro-de-r-316-mi-alta-anual-de-35\/","title":{"rendered":"Multiplan (MULT3) fecha 1\u00ba tri com lucro de R$ 316 mi, alta anual de 35%"},"content":{"rendered":"<p>Https<br \/>\nDeve Ler<br \/>\nA operadora de shopping centers e empreendimentos imobili\u00e1rios\u00a0<span id=\"CHAVE_72\" title=\"72\/9 | 798903\">Multiplan<\/span>\u00a0teve lucro l\u00edquido de R$316,14 milh\u00f5es no primeiro trimestre, crescimento de 35% na compara\u00e7\u00e3o com o mesmo per\u00edodo do ano passado, segundo balan\u00e7o divulgado nesta quarta-feira.<\/p>\n<p>A empresa teve um resultado operacional medido pelo lucro antes de juros, impostos, deprecia\u00e7\u00e3o e amortiza\u00e7\u00e3o (Ebitda) de R$516,48 milh\u00f5es de janeiro ao final de mar\u00e7o, alta de 29% sobre o mesmo per\u00edodo de 2025.<\/p>\n<p>A m\u00e9dia de previs\u00f5es de analistas do setor compilada pela LSEG apontava para lucro l\u00edquido de R$234,4 milh\u00f5es e Ebitda de R$463,2 milh\u00f5es.<\/p>\n<p>A receita operacional l\u00edquida sob o indicador NOI &#8211; importante na avalia\u00e7\u00e3o do desempenho de um shopping &#8211; somou R$477,2 milh\u00f5es ante R$465,4 milh\u00f5es no primeiro trimestre de 2025.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Https Deve Ler A operadora de shopping centers e empreendimentos imobili\u00e1rios\u00a0Multiplan\u00a0teve lucro l\u00edquido de R$316,14 milh\u00f5es no primeiro trimestre, crescimento de 35% na compara\u00e7\u00e3o com o mesmo per\u00edodo do ano &hellip; <a href=\"https:\/\/monitoramento.spmj.com.br\/noticias\/2026\/05\/04\/multiplan-mult3-fecha-1o-tri-com-lucro-de-r-316-mi-alta-anual-de-35\/\" class=\"more-link\">Continuar lendo <span class=\"screen-reader-text\">Multiplan (MULT3) fecha 1\u00ba tri com lucro de R$ 316 mi, alta anual de 35%<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[44],"tags":[],"class_list":["post-127956","post","type-post","status-publish","format-standard","hentry","category-shopping-patio-higienopolis"],"acf":[],"_links":{"self":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts\/127956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=127956"}],"version-history":[{"count":1,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts\/127956\/revisions"}],"predecessor-version":[{"id":127960,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts\/127956\/revisions\/127960"}],"wp:attachment":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=127956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=127956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=127956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}