{"id":127781,"date":"2026-04-28T12:47:25","date_gmt":"2026-04-28T15:47:25","guid":{"rendered":"https:\/\/monitoramento.spmj.com.br\/noticias\/?p=127781"},"modified":"2026-04-28T12:47:26","modified_gmt":"2026-04-28T15:47:26","slug":"nova-regra-muda-norma-para-supermercados-como-carrefour-e-assai-e-impoe-multa-rigorosa-entenda","status":"publish","type":"post","link":"https:\/\/monitoramento.spmj.com.br\/noticias\/2026\/04\/28\/nova-regra-muda-norma-para-supermercados-como-carrefour-e-assai-e-impoe-multa-rigorosa-entenda\/","title":{"rendered":"Nova regra muda norma para supermercados como Carrefour e Assa\u00ed e imp\u00f5e multa rigorosa; entenda"},"content":{"rendered":"<div class=\"ndmais-post-header col-xl-9 order-1 order-xl-2\">\n<p class=\"subtitle\">Lei em vigor obriga supermercados a oferecer atendimento especial a clientes e deve alterar funcionamento em estabelecimentos; saiba mais<\/p>\n<p><a id=\"single-whatsapp-action\" class=\"d-none d-xl-flex justify-content-between\" title=\"Seguir no WhatsApp\" href=\"https:\/\/ndmais.com.br\/whatsapp\/\"><\/a><\/div>\n<div class=\"ndmais-post-content col-xl-9 order-3\">\n<div class=\"entry-content single-content\" data-post-url=\"\/justica\/nova-lei-dos-supermercados-carrefour-e-assai-tem-novas-regras\/\" data-post-title=\"Nova regra muda norma para supermercados como Carrefour e Assa\u00ed e imp\u00f5e multa rigorosa; entenda\" data-mrf-recirculation=\"Article Content\">\n<div id=\"attachment_2844200\" class=\"wp-caption alignnone \" data-src=\"https:\/\/static.ndmais.com.br\/2026\/03\/nova-lei-impoe-proibicao-rigorosa-e-muda-atendimento-de-clientes-no-varejo-em-2026.jpg\">\n<div id=\"standard_1\" class=\"st-placement standard_1 inImageRestricted\">\n<div class=\"st-adunit st-adunit-tagged st-reset st-show\">\n<div class=\"st-adunit-ad st-reset\">\n<div class=\"st-display-render st-reset open 320x50\">\n<div class=\"st-canvas st-reset horizontal-static\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"content-first-image wp-image-2844200 size-full pp-add-seedtag\" src=\"https:\/\/static.ndmais.com.br\/2026\/03\/nova-lei-impoe-proibicao-rigorosa-e-muda-atendimento-de-clientes-no-varejo-em-2026.jpg\" alt=\"Nova lei dos supermercados imp\u00f5e proibi\u00e7\u00e3o rigorosa e muda atendimento de clientes em 2026\" width=\"1200\" height=\"700\" \/><span class=\"wp-caption-text\">Nova lei dos supermercados imp\u00f5e proibi\u00e7\u00e3o rigorosa e muda atendimento de clientes em 2026<span class=\"post-img-credit\">Foto: Montagem feita com imagens do Carrefour e do Assa\u00ed\/ND Mais<\/span><\/span><\/div>\n<p>Uma lei em vigor desde 2024 no\u00a0<a href=\"https:\/\/ndmais.com.br\/tag\/bahia\/\" data-mrf-link=\"https:\/\/ndmais.com.br\/tag\/bahia\/\">estado da Bahia<\/a>\u00a0passou a impor novas obriga\u00e7\u00f5es a\u00a0<a href=\"https:\/\/ndmais.com.br\/economia\/negocios\/nova-lei-para-supermercados-pode-punir-em-ate-r-10-mil\/\" data-mrf-link=\"https:\/\/ndmais.com.br\/economia\/negocios\/nova-lei-para-supermercados-pode-punir-em-ate-r-10-mil\/\">supermercados e grandes redes varejistas<\/a>, como Carrefour, Assa\u00ed e outros estabelecimentos.<\/p>\n<p>Segundo a recente legisla\u00e7\u00e3o, os mercados precisam ofertar atendimento especial para consumidores<a href=\"https:\/\/ndmais.com.br\/educacao\/direitos-garantidos-conheca-a-legislacao-para-inclusao-de-pessoas-com-deficiencia\/\" data-mrf-link=\"https:\/\/ndmais.com.br\/educacao\/direitos-garantidos-conheca-a-legislacao-para-inclusao-de-pessoas-com-deficiencia\/\">\u00a0com defici\u00eancia<\/a> ou mobilidade reduzida durante o hor\u00e1rio de funcionamento.<\/p>\n<div class=\"galeria-de-fotos-slider single-section post-format-noticia\">\n<div class=\"slider-galeria-de-foto-container glide s0 glide--ltr glide--slider glide--swipeable\"><\/div>\n<\/div>\n<p>A regulamenta\u00e7\u00e3o visa ampliar o alcance de pol\u00edticas de inclus\u00e3o no varejo e refor\u00e7ar a\u00a0<a href=\"https:\/\/ndmais.com.br\/cidadania\/simbolo-internacional-de-acessibilidade\/\" data-mrf-link=\"https:\/\/ndmais.com.br\/cidadania\/simbolo-internacional-de-acessibilidade\/\">acessibilidade<\/a>\u00a0dentro de estabelecimentos de grande circula\u00e7\u00e3o.<\/p>\n<p><a class=\"cta-discover d-flex justify-content-between align-items-center w-100\" href=\"https:\/\/profile.google.com\/cp\/Cg0vZy8xMXZ5cjY4NHho\" target=\"_blank\" rel=\"nofollow noopner noopener\" data-mrf-link=\"https:\/\/profile.google.com\/cp\/Cg0vZy8xMXZ5cjY4NHho\"><span class=\"cta-discover-message d-flex flex-wrap justify-content-start align-items-center\"><i class=\"cta-discover-icon bi bi-google d-block\"><\/i><span class=\"cta-discover-text flex-grow-1\">Fa\u00e7a como milh\u00f5es de leitores informados: siga o ND Mais no Google.<\/span><\/span><\/a><\/p>\n<h2>O que muda com a nova lei dos supermercados<\/h2>\n<p class=\"ndmais_video_slider\">A\u00a0<a href=\"https:\/\/leisestaduais.com.br\/ba\/lei-ordinaria-n-14771-2024-bahia-dispoe-sobre-a-prestacao-de-auxilio-as-pessoas-com-deficiencia-e-ou-mobilidade-reduzida-nos-supermercados-lojas-de-departamentos-e-estabelecimentos-congeneres-do-estado-da-bahia-e-da-outras-providencias?q=n%C2%BA+2.+848\" target=\"_blank\" rel=\"noopener\" data-mrf-link=\"https:\/\/leisestaduais.com.br\/ba\/lei-ordinaria-n-14771-2024-bahia-dispoe-sobre-a-prestacao-de-auxilio-as-pessoas-com-deficiencia-e-ou-mobilidade-reduzida-nos-supermercados-lojas-de-departamentos-e-estabelecimentos-congeneres-do-estado-da-bahia-e-da-outras-providencias?q=n%C2%BA+2.+848\" data-mrf-recirculation-id=\"Article Content_6\">Lei n\u00ba 14.771\/2024\u00a0<\/a> determina que supermercados, hipermercados, minimercados e lojas de departamento disponibilizem funcion\u00e1rios capacitados para auxiliar clientes que necessitem de apoio durante as compras.<\/p>\n<div class=\"PRA_VIDEO\" data-yield-master-placement-inserted=\"\">\n<div>\n<div id=\"notsy_container_969721984\" class=\"NDM_VIDEO\" data-notsy-container-index=\"1\" data-notsy-mapped-container=\"1\" data-ym-video-sticky-mode=\"1\">\n<div>\n<div id=\"video_16365-container\" class=\"nts-container\" data-mobile=\"0\">\n<div id=\"video_16365-sub-container\" class=\"ym-video--sub-container\">\n<div id=\"video_16365-float-container\" class=\"nts-float-container ym-float-container__sticky\">\n<div class=\"ym-video-sticky-close ym-video-sticky-close__md ym-video-sticky-close__square ym-video-sticky-close__top-left-side\">\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>O atendimento deve ser oferecido sempre que solicitado e abrange suporte em diferentes etapas da perman\u00eancia do consumidor no estabelecimento.<\/p>\n<div id=\"attachment_2876183\" class=\"wp-caption alignnone \" data-src=\"https:\/\/static.ndmais.com.br\/2026\/04\/nova-regra-muda-norma-para-supermercados-como-carrefour-e-assai-e-impoe-multa-rigorosa-entenda.jpg\">\n<div id=\"standard_2\" class=\"st-placement standard_2 inImageRestricted\">\n<div class=\"st-adunit st-adunit-tagged st-reset st-show\">\n<div class=\"st-adunit-ad st-reset\"><\/div>\n<\/div>\n<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2876183 pp-add-seedtag\" src=\"https:\/\/static.ndmais.com.br\/2026\/04\/nova-regra-muda-norma-para-supermercados-como-carrefour-e-assai-e-impoe-multa-rigorosa-entenda.jpg\" alt=\"Nova lei dos supermercados muda norma para grandes redes como Carrefour e Assa\u00ed\u00a0Foto: Montagem feita com imagens das redes sociais e do Assa\u00ed\/ND Mais\" width=\"1200\" height=\"700\" \/><span class=\"wp-caption-text\">Nova lei dos supermercados muda norma para grandes redes como Carrefour e Assa\u00ed\u00a0<span class=\"post-img-credit\">Foto: Montagem feita com imagens das redes sociais e do Assa\u00ed\/ND Mais<\/span><\/span><\/div>\n<p class=\"ndmais_video_outstream\">Al\u00e9m disso, a exig\u00eancia prevista n\u00e3o incluiu com\u00e9rcios menores com at\u00e9 10 funcion\u00e1rios.<\/p>\n<h2>Aux\u00edlios ofertados<\/h2>\n<p>A norma estabelece que o suporte precisa ser pr\u00e1tico e adaptado \u00e0s necessidades do cliente. Entre os servi\u00e7os obrigat\u00f3rios est\u00e3o:<\/p>\n<ul>\n<li>acompanhar o consumidor no interior da loja;<\/li>\n<li>indicar a localiza\u00e7\u00e3o de produtos;<\/li>\n<li>auxiliar no uso do carrinho de compras;<\/li>\n<li>retirar e acomodar itens no carrinho;<\/li>\n<li>informar pre\u00e7os, validade e caracter\u00edsticas dos produtos;<\/li>\n<li>ajudar no empacotamento e no transporte das compras.<\/li>\n<\/ul>\n<p class=\"ndmais_intext\" data-ad-unit=\"NDMAIS_INTEXT_02\">Segundo a regra, o pedido de atendimento pode ser feito diretamente no balc\u00e3o de atendimento ao cliente.<\/p>\n<p>Caso o estabelecimento n\u00e3o tenha esse espa\u00e7o espec\u00edfico, a solicita\u00e7\u00e3o pode ser feita a qualquer funcion\u00e1rio dispon\u00edvel. Al\u00e9m disso, a lei obriga os estabelecimentos a informar esse direito ao consumidor por meio de cartazes em locais vis\u00edveis.<\/p>\n<h2>Multas podem chegar a R$ 10 mil<\/h2>\n<p>O descumprimento da regra pode gerar penalidades financeiras para os estabelecimentos. Segundo previsto na legisla\u00e7\u00e3o, a\u00a0multa inicial foi fixada em R$ 2 mil, mas pode atingir R$ 10 mil em caso de reincid\u00eancia.<\/p>\n<p class=\"ndmais_intext\" data-ad-unit=\"NDMAIS_INTEXT_03\">Os valores arrecadados ser\u00e3o destinados ao COEDE\/BA (Conselho Estadual dos Direitos da Pessoa com Defici\u00eancia da Bahia), \u00f3rg\u00e3o respons\u00e1vel por pol\u00edticas voltadas \u00e0 inclus\u00e3o e garantia de direitos.<\/p>\n<div id=\"P_NDMAIS_INTEXT_03_0\" data-premium=\"\" data-adunit=\"NDMAIS_INTEXT_03\" data-sizes-desktop=\"[[336,280],[300,250]]\" data-sizes-mobile=\"[[336,280],[300,250]]\" data-fetch=\"true\" data-google-query-id=\"CLWfkf_xkJQDFSY3uQYdwugqpA\">\n<div id=\"google_ads_iframe_\/24827565\/NDMAIS_INTEXT_03_0__container__\"><span style=\"font-size: 29px;font-weight: bold\">Fiscaliza\u00e7\u00e3o em varejos<\/span><\/div>\n<\/div>\n<p>A fiscaliza\u00e7\u00e3o da nova regra \u00e9 responsabilidade de \u00f3rg\u00e3os estaduais e o monitoramento pode ocorrer por inspe\u00e7\u00f5es presenciais ou den\u00fancias feitas por consumidores.<\/p>\n<p>Esses mecanismos permitem que o cumprimento da lei seja acompanhado diretamente pela administra\u00e7\u00e3o p\u00fablica.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Uma lei em vigor desde 2024 no\u00a0estado da Bahia\u00a0passou a impor novas obriga\u00e7\u00f5es a\u00a0supermercados e grandes redes varejistas, como Carrefour, Assa\u00ed e outros estabelecimentos.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-127781","post","type-post","status-publish","format-standard","hentry","category-l-founders"],"acf":[],"_links":{"self":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts\/127781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=127781"}],"version-history":[{"count":1,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts\/127781\/revisions"}],"predecessor-version":[{"id":127782,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts\/127781\/revisions\/127782"}],"wp:attachment":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=127781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=127781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=127781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}