{"id":125467,"date":"2026-03-11T12:30:05","date_gmt":"2026-03-11T15:30:05","guid":{"rendered":"https:\/\/monitoramento.spmj.com.br\/noticias\/?p=125467"},"modified":"2026-03-11T12:30:05","modified_gmt":"2026-03-11T15:30:05","slug":"raizen-e-gpa-pedem-recuperacao-extrajudicial-entenda-as-diferencas-entre-os-processos","status":"publish","type":"post","link":"https:\/\/monitoramento.spmj.com.br\/noticias\/2026\/03\/11\/raizen-e-gpa-pedem-recuperacao-extrajudicial-entenda-as-diferencas-entre-os-processos\/","title":{"rendered":"Ra\u00edzen e GPA pedem recupera\u00e7\u00e3o extrajudicial; entenda as diferen\u00e7as entre os processos"},"content":{"rendered":"<div class=\"mc-article-header\">\n<div class=\"row content-head mc-column non-featured \">\n<div class=\"medium-centered subtitle\">\n<h2 class=\"content-head__subtitle\">Empresas buscam renegociar d\u00edvidas com credores fora da Justi\u00e7a; especialistas explicam como funciona o mecanismo e o que distingue as situa\u00e7\u00f5es das duas empresas.<\/h2>\n<\/div>\n<\/div>\n<div class=\"content__signa-share mc-column\">\n<div class=\"content__signature\">\n<div class=\"content-publication-data\">\n<div class=\"content-publication-data__text\">\n<p class=\"content-publication-data__from\" title=\"Reda\u00e7\u00e3o g1\">Por\u00a0<a class=\"multi_signatures\" href=\"https:\/\/g1.globo.com\/autores\/redacao-g1\/\">Reda\u00e7\u00e3o g1<\/a>\u00a0\u2014 S\u00e3o Paulo<\/p>\n<p class=\"content-publication-data__updated\">11\/03\/2026 10h01\u00a0<span class=\"content-publication-data__updated-relative\">\u00a0Atualizado\u00a0h\u00e1 uma hora<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mc-summary mc-column\" data-block-type=\"summary\" data-block-id=\"1\">\n<details class=\"mc-summary-card bs-block--exclude-chunk-children\">\n<div class=\"mc-summary-card__summary-container\"><\/div>\n<div class=\"mc-summary-card__content\">\n<ul class=\"mc-summary-card__list\">\n<li class=\"mc-summary-card__item\">\n<div id=\"chunk-64tan\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Mat\u00e9ria - Links no Texto\">Ra\u00edzen e Grupo P\u00e3o de A\u00e7\u00facar (GPA) entraram com pedidos de recupera\u00e7\u00e3o extrajudicial.<\/p>\n<\/div>\n<\/div>\n<\/li>\n<li class=\"mc-summary-card__item\">\n<div id=\"chunk-mq5a\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Mat\u00e9ria - Links no Texto\">As duas empresas recorreram ao mecanismo com o objetivo de renegociar d\u00edvidas com credores, reestruturar passivos e refor\u00e7ar o caixa.<\/p>\n<\/div>\n<\/div>\n<\/li>\n<li class=\"mc-summary-card__item\">\n<div id=\"chunk-e8fdv\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Mat\u00e9ria - Links no Texto\">Embora atuem em setores diferentes, os casos chamam aten\u00e7\u00e3o pelo porte das companhias e pelo volume de d\u00edvidas envolvido.<\/p>\n<\/div>\n<\/div>\n<\/li>\n<li class=\"mc-summary-card__item\">\n<div id=\"chunk-b7nvm\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Mat\u00e9ria - Links no Texto\">A recupera\u00e7\u00e3o extrajudicial \u00e9 um mecanismo legal que permite \u00e0 empresa em crise financeira renegociar uma parte espec\u00edfica de suas d\u00edvidas.<\/p>\n<\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<\/details>\n<\/div>\n<\/div>\n<div class=\"mc-article-body\">\n<article>\n<div id=\"chunk-erh62\">\n<div class=\"cxm-block-video content-media mc-column \" data-block-type=\"backstage-video\" data-block-id=\"2\">\n<div class=\"cxm-block-video__container cxm-block-video__container--fallback \">\n<div class=\"cxm-block-video__player-fixer\">\n<article class=\"cxm-block-video__player-wrapper\">\n<section class=\"cxm-block-video__player\">\n<div class=\"cxm-block-video__placeholder\" data-video-id=\"14418732\"><img decoding=\"async\" class=\"cxm-block-video__thumb\" title=\"Ra\u00edzen e Grupo P\u00e3o de A\u00e7\u00facar pedem recupera\u00e7\u00e3o extrajudicial\" src=\"https:\/\/s01.video.glbimg.com\/x240\/14418732.jpg\" alt=\"Ra\u00edzen e Grupo P\u00e3o de A\u00e7\u00facar pedem recupera\u00e7\u00e3o extrajudicial\" \/><\/p>\n<div>\n<div id=\"wp3-player-1\" class=\"clappr-player video-rec-after-end--enabled clappr-detach--is-detached clappr-detach--is-detached__visible\" data-player=\"\" data-compass-listening=\"true\">\n<div class=\"dfp-ad-overlay dfp-ad-overlay--poster-mode\">\n<div><\/div>\n<\/div>\n<div class=\"frame-ad h720 w360\">Ra\u00edzen e Grupo P\u00e3o de A\u00e7\u00facar pedem recupera\u00e7\u00e3o extrajudicial<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"chunk-ercid\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"46\" data-block-id=\"4\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Mat\u00e9ria - Links no Texto\">No intervalo de dois dias, duas grandes empresas brasileiras entraram com pedidos de recupera\u00e7\u00e3o extrajudicial: o\u00a0<a class=\"\" href=\"https:\/\/g1.globo.com\/economia\/noticia\/2026\/03\/10\/gpa-plano-de-recuperacao-extrajudicial.ghtml\" data-mrf-link=\"https:\/\/g1.globo.com\/economia\/noticia\/2026\/03\/10\/gpa-plano-de-recuperacao-extrajudicial.ghtml\"><strong>Grupo P\u00e3o de A\u00e7\u00facar (GPA)<\/strong><\/a>\u00a0e a\u00a0<a class=\"\" href=\"https:\/\/g1.globo.com\/economia\/noticia\/2026\/03\/11\/raizen-recuperacao-extrajudicial.ghtml\" data-mrf-link=\"https:\/\/g1.globo.com\/economia\/noticia\/2026\/03\/11\/raizen-recuperacao-extrajudicial.ghtml\"><strong>Ra\u00edzen<\/strong><\/a>, companhia l\u00edder na produ\u00e7\u00e3o de a\u00e7\u00facar e etanol no Brasil e fruto de uma parceria entre o grupo Cosan e a Shell.<\/p>\n<\/div>\n<\/div>\n<div class=\"wall protected-content\">\n<div id=\"chunk-5eslm\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"39\" data-block-id=\"5\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Mat\u00e9ria - Links no Texto\">As duas empresas recorreram ao mecanismo com o objetivo de renegociar d\u00edvidas com credores, reestruturar passivos e refor\u00e7ar o caixa. Embora atuem em setores diferentes, os casos chamam aten\u00e7\u00e3o pelo porte das companhias e pelo volume de d\u00edvidas envolvido.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-a34ne\">\n<div class=\"mc-column content-text active-extra-styles\" data-block-type=\"raw\" data-block-weight=\"47\" data-block-id=\"6\">\n<ul class=\"content-unordered-list\" data-mrf-recirculation=\"Mat\u00e9ria - Leia Tamb\u00e9m (Lista)\">\n<li><em> A recupera\u00e7\u00e3o extrajudicial \u00e9 um acordo no qual a empresa renegocia parte das d\u00edvidas diretamente com alguns credores, fora da Justi\u00e7a. O objetivo \u00e9 obter mais prazo ou melhores condi\u00e7\u00f5es de pagamento para reorganizar as finan\u00e7as e evitar problemas mais graves, como o risco de fal\u00eancia.<\/em><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div id=\"chunk-a560s\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"14\" data-block-id=\"8\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Mat\u00e9ria - Links no Texto\"><strong><span class=\"highlight highlighted\">Abaixo, o\u00a0<\/span><\/strong><a class=\"\" href=\"https:\/\/g1.globo.com\/\" data-mrf-link=\"https:\/\/g1.globo.com\/\"><strong><span class=\"highlight highlighted\">g1<\/span><\/strong><\/a><strong><span class=\"highlight highlighted\">\u00a0explica ambos os casos e como funciona uma recupera\u00e7\u00e3o extrajudicial:<\/span><\/strong><\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-83peg\">\n<div class=\"mc-column content-text active-extra-styles\" data-block-type=\"raw\" data-block-weight=\"2\" data-block-id=\"9\">\n<p class=\"content-text__container\" data-mrf-recirculation=\"Mat\u00e9ria - Links no Texto\">\n<div class=\"content-intertitle\">\n<h2><strong>Caso Ra\u00edzen<\/strong><\/h2>\n<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-8dqd5\">\n<div class=\"row medium-uncollapsed content-media content-photo\" data-block-type=\"backstage-photo\" data-block-id=\"10\">\n<div class=\" mc-column  content-media__container\">\n<div class=\"content-media-container glb-skeleton-box\">\n<figure class=\"content-media-figure\"><img decoding=\"async\" class=\"i-amphtml-fill-content i-amphtml-replaced-content\" src=\"https:\/\/s2-g1.glbimg.com\/_UBFTQ7YBUypmAFXt-YCB8ROMBI=\/0x0:772x513\/984x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2023\/T\/P\/86hfKvTYm3WBWvAn7YXQ\/raizen.jpg\" alt=\"Ra\u00edzen \u2014 Foto: Divulga\u00e7\u00e3o\" \/><\/figure>\n<\/div>\n<p class=\"content-media__description  \">Ra\u00edzen \u2014 Foto: Divulga\u00e7\u00e3o<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"chunk-7s62u\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"34\" data-block-id=\"11\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Mat\u00e9ria - Links no Texto\">A Ra\u00edzen anunciou nesta quarta-feira (11) que\u00a0<a class=\"\" href=\"https:\/\/g1.globo.com\/economia\/noticia\/2026\/03\/11\/raizen-recuperacao-extrajudicial.ghtml\" data-mrf-link=\"https:\/\/g1.globo.com\/economia\/noticia\/2026\/03\/11\/raizen-recuperacao-extrajudicial.ghtml\"><strong>entrou com pedido de recupera\u00e7\u00e3o extrajudicial na Comarca da Capital de S\u00e3o Paulo<\/strong><\/a>, em meio \u00e0s negocia\u00e7\u00f5es com credores para reestruturar suas d\u00edvidas e refor\u00e7ar o caixa.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-1s1ti\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"36\" data-block-id=\"12\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Mat\u00e9ria - Links no Texto\">Segundo a empresa, o plano foi estruturado em acordo com seus principais credores quirograf\u00e1rios \u2013 aqueles que t\u00eam valores a receber, mas n\u00e3o possuem garantias espec\u00edficas, como im\u00f3veis ou outros bens dados como garantia da d\u00edvida.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-15h87\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"32\" data-block-id=\"13\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Mat\u00e9ria - Links no Texto\">O objetivo \u00e9 criar um ambiente jur\u00eddico mais seguro para reorganizar as d\u00edvidas financeiras do grupo, que somam cerca de\u00a0<strong>R$ 65,1 bilh\u00f5es<\/strong>, al\u00e9m de valores devidos entre empresas da pr\u00f3pria companhia.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-esveb\">\n<div class=\"content-ads content-ads--reveal\" data-block-type=\"ads\" data-block-id=\"14\">\n<div id=\"banner_materia__9e898886-eb0d-47a2-a0fb-5fb20dd882b9\">\n<div id=\"google_ads_iframe_\/95377733\/tvg_G1\/Economia_4__container__\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"chunk-cjmhv\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"33\" data-block-id=\"15\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Mat\u00e9ria - Links no Texto\">De acordo com a Ra\u00edzen, o plano j\u00e1 conta com a ades\u00e3o de credores que\u00a0<strong>representam mais de 47% das d\u00edvidas financeiras sem garantia<\/strong>, percentual suficiente para protocolar o pedido de recupera\u00e7\u00e3o extrajudicial.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-921id\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"48\" data-block-id=\"16\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Mat\u00e9ria - Links no Texto\"><span class=\"highlight highlighted\">A partir de agora, a empresa ter\u00e1 at\u00e9 90 dias para ampliar a ades\u00e3o de credores ao plano e alcan\u00e7ar o percentual m\u00ednimo exigido para que a Justi\u00e7a homologue a proposta. Com a homologa\u00e7\u00e3o, o plano passa a valer para todos os titulares dos cr\u00e9ditos inclu\u00eddos na negocia\u00e7\u00e3o.<\/span><\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-dtp4i\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"27\" data-block-id=\"17\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Mat\u00e9ria - Links no Texto\">Entre as medidas previstas est\u00e3o inje\u00e7\u00e3o de recursos pelos acionistas, convers\u00e3o de parte das d\u00edvidas em a\u00e7\u00f5es, alongamento de prazos de pagamento e eventual venda de ativos.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-77db2\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"28\" data-block-id=\"18\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Mat\u00e9ria - Links no Texto\">A companhia afirmou ainda que o processo tem\u00a0<strong>escopo apenas financeiro e n\u00e3o inclui d\u00edvidas com clientes, fornecedores, revendedores ou outros parceiros comerciais<\/strong>, que continuar\u00e3o sendo pagos normalmente.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-5d2r2\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"33\" data-block-id=\"19\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Mat\u00e9ria - Links no Texto\">A empresa de a\u00e7\u00facar, etanol e distribui\u00e7\u00e3o de combust\u00edveis enfrenta press\u00e3o financeira ap\u00f3s ver sua\u00a0<strong>receita diminuir e a d\u00edvida l\u00edquida atingir R$ 55,3 bilh\u00f5es no fim de dezembro<\/strong>, segundo dados divulgados anteriormente.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-3alhi\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"25\" data-block-id=\"20\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Mat\u00e9ria - Links no Texto\">Nos \u00faltimos dias, a controladora Cosan j\u00e1 indicava que uma solu\u00e7\u00e3o para a situa\u00e7\u00e3o da companhia poderia ser anunciada em breve, segundo informa\u00e7\u00f5es da Reuters.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>No intervalo de dois dias, duas grandes empresas brasileiras entraram com pedidos de recupera\u00e7\u00e3o extrajudicial: o Grupo P\u00e3o de A\u00e7\u00facar (GPA) e a Ra\u00edzen, companhia l\u00edder na produ\u00e7\u00e3o de a\u00e7\u00facar e etanol no Brasil e fruto de uma parceria entre o grupo Cosan e a Shell.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56,62],"tags":[],"class_list":["post-125467","post","type-post","status-publish","format-standard","hentry","category-l-founders","category-pao-de-acucar"],"acf":[],"_links":{"self":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts\/125467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=125467"}],"version-history":[{"count":1,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts\/125467\/revisions"}],"predecessor-version":[{"id":125468,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts\/125467\/revisions\/125468"}],"wp:attachment":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=125467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=125467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=125467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}