{"id":119049,"date":"2025-09-23T08:48:11","date_gmt":"2025-09-23T11:48:11","guid":{"rendered":"https:\/\/monitoramento.spmj.com.br\/noticias\/?p=119049"},"modified":"2025-09-23T08:48:11","modified_gmt":"2025-09-23T11:48:11","slug":"onde-encontrar-as-melhores-tortas-de-limao-em-sao-paulo-mencao","status":"publish","type":"post","link":"https:\/\/monitoramento.spmj.com.br\/noticias\/2025\/09\/23\/onde-encontrar-as-melhores-tortas-de-limao-em-sao-paulo-mencao\/","title":{"rendered":"Onde encontrar as melhores tortas de lim\u00e3o em S\u00e3o Paulo &#8211; Men\u00e7\u00e3o"},"content":{"rendered":"<div class=\"featured-area\">\n<div class=\"featured-area-inner\">\n<figure class=\"single-featured-image\"><img loading=\"lazy\" decoding=\"async\" class=\"attachment-full size-full wp-post-image lazy loaded\" src=\"https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/La-Cura_Gui-Galembeck-2-1-scaled.jpg\" alt=\"\" width=\"1829\" height=\"2560\" data-src=\"https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/La-Cura_Gui-Galembeck-2-1-scaled.jpg\" data-main-img=\"1\" data-srcset=\"https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/La-Cura_Gui-Galembeck-2-1-scaled.jpg 1829w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/La-Cura_Gui-Galembeck-2-1-214x300.jpg 214w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/La-Cura_Gui-Galembeck-2-1-731x1024.jpg 731w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/La-Cura_Gui-Galembeck-2-1-768x1075.jpg 768w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/La-Cura_Gui-Galembeck-2-1-1097x1536.jpg 1097w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/La-Cura_Gui-Galembeck-2-1-1463x2048.jpg 1463w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/La-Cura_Gui-Galembeck-2-1-600x840.jpg 600w\" data-sizes=\"(max-width: 1829px) 100vw, 1829px\" data-was-processed=\"true\" \/><\/figure>\n<\/div>\n<\/div>\n<div class=\"entry-content entry clearfix\">\n<p>Amada por todos, a cl\u00e1ssica e queridinha torta de lim\u00e3o n\u00e3o cansa de surpreender o paladar. Por isso, a Prazeres da Mesa separou um roteiro de onde encontrar as melhores tortas e suas varia\u00e7\u00f5es pela cidade de S\u00e3o Paulo:<\/p>\n<h2 id=\"h-a-torteria\" class=\"wp-block-heading\">A Torteria<\/h2>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-116966 lazy loaded\" src=\"https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/torta-de-limao-683x1024.jpg\" alt=\"\" width=\"683\" height=\"1024\" data-src=\"https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/torta-de-limao-683x1024.jpg\" data-srcset=\"https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/torta-de-limao-683x1024.jpg 683w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/torta-de-limao-200x300.jpg 200w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/torta-de-limao-768x1152.jpg 768w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/torta-de-limao-1024x1536.jpg 1024w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/torta-de-limao-600x900.jpg 600w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/torta-de-limao.jpg 1067w\" data-sizes=\"(max-width: 683px) 100vw, 683px\" data-was-processed=\"true\" \/><figcaption class=\"wp-element-caption\">Torta de lim\u00e3o siciliano e chocolate branco | Foto: Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<\/div>\n<p>Com base de leite condensado com lim\u00e3o siciliano, chocolate branco e curd de lim\u00e3o siciliano, a torta est\u00e1 disp\u00f3n\u00edvel em fatia (R$ 22), tamanho M (R$ 110) e tamanho G (R$ 159)<\/p>\n<p>Endere\u00e7os: R. Fradique Coutinho, 39 \u2013 Pinheiros | R. Sabar\u00e1, 585 \u2013 Consola\u00e7\u00e3o | Rua dos Tr\u00eas Irm\u00e3os, 654 \u2013 Vila Progredior | Tel.: +55 11 94594-3042 |\u00a0<a href=\"https:\/\/atorteria.com.br\/torteria\">https:\/\/atorteria.com.br\/torteria<\/a>\u00a0|\u00a0<a href=\"https:\/\/www.instagram.com\/atorteria\/\">@atorteria<\/a><\/p>\n<div class=\"stream-item stream-item-in-post stream-item-inline-post aligncenter\"><span class=\"stream-title\">Continua ap\u00f3s o an\u00fancio<\/span><\/p>\n<div class=\"stream-item-size\"><\/div>\n<\/div>\n<h2 id=\"h-la-cura\" class=\"wp-block-heading\">LA CURA<\/h2>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-116967 lazy loaded\" src=\"https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/La-Cura_Gui-Galembeck-2-1-731x1024.jpg\" alt=\"\" width=\"731\" height=\"1024\" data-src=\"https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/La-Cura_Gui-Galembeck-2-1-731x1024.jpg\" data-srcset=\"https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/La-Cura_Gui-Galembeck-2-1-731x1024.jpg 731w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/La-Cura_Gui-Galembeck-2-1-214x300.jpg 214w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/La-Cura_Gui-Galembeck-2-1-768x1075.jpg 768w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/La-Cura_Gui-Galembeck-2-1-1097x1536.jpg 1097w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/La-Cura_Gui-Galembeck-2-1-1463x2048.jpg 1463w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/La-Cura_Gui-Galembeck-2-1-600x840.jpg 600w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/La-Cura_Gui-Galembeck-2-1-scaled.jpg 1829w\" data-sizes=\"(max-width: 731px) 100vw, 731px\" data-was-processed=\"true\" \/><figcaption class=\"wp-element-caption\">Foto: Gui Galembeck<\/figcaption><\/figure>\n<\/div>\n<p>Na La Cura, rotisserie do chef Ivan Santinho, localizada na Vila Madalena, a Torta de Lim\u00e3o tem massa crocante de castanhas do Par\u00e1, \u00e9 recheada com camadas de curd de lim\u00e3o siciliano e creme de lim\u00e3o taiti, e coberta com merengue italiano e frutas vermelhas frescas. Pode ser encontrada em tamanho individual (R$22) ou grande, para compartilhar (R$190).<\/p>\n<p>Endere\u00e7o: Rua Our\u00e2nia, 201A \u2013 Vila Madalena | Tel.: (11) 94140-2824 |\u00a0<a href=\"https:\/\/www.instagram.com\/lacuragastronomia\/\">@lacuragastronomia<\/a><\/p>\n<h2 id=\"h-confeitaria-dama\" class=\"wp-block-heading\">Confeitaria DAMA<\/h2>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-116969 lazy loaded\" src=\"https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/DAMA_Ricardo-DAngelo-1-683x1024.jpg\" alt=\"\" width=\"683\" height=\"1024\" data-src=\"https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/DAMA_Ricardo-DAngelo-1-683x1024.jpg\" data-srcset=\"https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/DAMA_Ricardo-DAngelo-1-683x1024.jpg 683w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/DAMA_Ricardo-DAngelo-1-200x300.jpg 200w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/DAMA_Ricardo-DAngelo-1-768x1152.jpg 768w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/DAMA_Ricardo-DAngelo-1-1024x1536.jpg 1024w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/DAMA_Ricardo-DAngelo-1-1365x2048.jpg 1365w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/DAMA_Ricardo-DAngelo-1-600x900.jpg 600w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/DAMA_Ricardo-DAngelo-1-scaled.jpg 1707w\" data-sizes=\"(max-width: 683px) 100vw, 683px\" data-was-processed=\"true\" \/><figcaption class=\"wp-element-caption\">Foto: Ricardo D&#8217;Angelo<\/figcaption><\/figure>\n<\/div>\n<p>Na Confeitaria DAMA, das s\u00f3cias Daniela e Mariana Gorski, a Torta de Lim\u00e3o segue a linha mais cl\u00e1ssica: tem base de farinha de castanhas, \u00e9 recheada de creme de lim\u00e3o e recebe merengue. Pode ser encontrada em tamanho de tartelete p\u00e2tisserie (R$11,50), torta individual (R$29,50) ou de 22cm (R$220).<\/p>\n<p>Rua Ferreira de Ara\u00fajo, 376 | Whatsapp (11) 97095-3888; Fixo (11) 5182-5088 |\u00a0<a href=\"https:\/\/www.confeitariadama.com.br\/\">https:\/\/www.confeitariadama.com.br\/<\/a>\u00a0|\u00a0<a href=\"https:\/\/www.instagram.com\/confeitariadama\/\">@confeitariadama<\/a><\/p>\n<h2 id=\"h-pao-de-queijo-haddock-lobo\" class=\"wp-block-heading\">P\u00e3o de Queijo Haddock Lobo<\/h2>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-116971 lazy loaded\" src=\"https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/IMG_2023-copiar-1-683x1024.jpg\" alt=\"\" width=\"683\" height=\"1024\" data-src=\"https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/IMG_2023-copiar-1-683x1024.jpg\" data-srcset=\"https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/IMG_2023-copiar-1-683x1024.jpg 683w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/IMG_2023-copiar-1-200x300.jpg 200w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/IMG_2023-copiar-1-768x1152.jpg 768w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/IMG_2023-copiar-1-1024x1536.jpg 1024w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/IMG_2023-copiar-1-1365x2048.jpg 1365w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/IMG_2023-copiar-1-600x900.jpg 600w, https:\/\/www.prazeresdamesa.com.br\/wp-content\/uploads\/2025\/09\/IMG_2023-copiar-1-scaled.jpg 1707w\" data-sizes=\"(max-width: 683px) 100vw, 683px\" data-was-processed=\"true\" \/><\/figure>\n<\/div>\n<p>Mini torta de lim\u00e3o \u2013 R$ 20<br \/>\nTorta de lim\u00e3o pequena \u2013 R$ 32<br \/>\nTorta de lim\u00e3o 300g \u2013 R$ 98<br \/>\nTorta de lim\u00e3o 1kg \u2013 R$ 260<\/p>\n<p>Rua Haddock Lobo, 1408, Shopping P\u00e1tio Higien\u00f3polis \u2013 piso Pacaembu | Tel.: (11) 96900-1600 |\u00a0<a href=\"https:\/\/paodequeijohaddocklobo.com.br\/\">https:\/\/paodequeijohaddocklobo.com.br\/<\/a>\u00a0| @paodequeijohaddocklobo<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Amada por todos, a cl\u00e1ssica e queridinha torta de lim\u00e3o n\u00e3o cansa de surpreender o paladar. Por isso, a Prazeres da Mesa separou um roteiro de onde encontrar as melhores tortas e suas varia\u00e7\u00f5es pela cidade de S\u00e3o Paulo: (Rua Haddock Lobo, 1408, Shopping P\u00e1tio Higien\u00f3polis \u2013 piso Pacaembu | Tel.: (11) 96900-1600 |\u00a0https:\/\/paodequeijohaddocklobo.com.br\/\u00a0| @paodequeijohaddocklobo)<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[44],"tags":[],"class_list":["post-119049","post","type-post","status-publish","format-standard","hentry","category-shopping-patio-higienopolis"],"acf":[],"_links":{"self":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts\/119049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=119049"}],"version-history":[{"count":1,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts\/119049\/revisions"}],"predecessor-version":[{"id":119050,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts\/119049\/revisions\/119050"}],"wp:attachment":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=119049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=119049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=119049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}