{"id":118791,"date":"2025-09-17T08:49:00","date_gmt":"2025-09-17T11:49:00","guid":{"rendered":"https:\/\/monitoramento.spmj.com.br\/noticias\/?p=118791"},"modified":"2025-09-17T08:49:00","modified_gmt":"2025-09-17T11:49:00","slug":"empresa-nao-pode-demitir-trabalhador-por-postagem-politica-mas-ha-excecoes-entenda","status":"publish","type":"post","link":"https:\/\/monitoramento.spmj.com.br\/noticias\/2025\/09\/17\/empresa-nao-pode-demitir-trabalhador-por-postagem-politica-mas-ha-excecoes-entenda\/","title":{"rendered":"Empresa n\u00e3o pode demitir trabalhador por postagem pol\u00edtica, mas h\u00e1 exce\u00e7\u00f5es; entenda"},"content":{"rendered":"<p>As empresas brasileiras s\u00e3o proibidas por lei de\u00a0<a href=\"https:\/\/www1.folha.uol.com.br\/poder\/2023\/09\/assessora-de-anielle-que-ofendeu-paulistas-e-sao-paulinos-e-demitida.shtml\" target=\"\" rel=\"noopener\">demitir funcion\u00e1rio por expressar opini\u00e3o pol\u00edtica<\/a>\u00a0nas redes sociais ou fora delas, desde que n\u00e3o haja incita\u00e7\u00e3o a crime ou\u00a0<a href=\"https:\/\/www1.folha.uol.com.br\/folha-topicos\/violencia\/\">viol\u00eancia<\/a>.<\/p>\n<p>A pr\u00e1tica, prevista na lei\u00a0<a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/leis\/l9029.htm\" target=\"_blank\" rel=\"nofollow noopener\">9.029<\/a>, de 1995, \u00e9 conhecida como dispensa discriminat\u00f3ria e pode levar a condena\u00e7\u00f5es na Justi\u00e7a do Trabalho, como reintegra\u00e7\u00e3o do profissional; multa no valor de duas vezes o sal\u00e1rio pelo per\u00edodo em que ele ficar afastado, mais juros e corre\u00e7\u00e3o monet\u00e1ria; e indeniza\u00e7\u00e3o por dano moral.<\/p>\n<p>O movimento &#8220;demita um extremista&#8221; vem crescendo nas redes sociais ap\u00f3s a\u00a0<a href=\"https:\/\/www1.folha.uol.com.br\/mundo\/2025\/09\/influenciador-trumpista-charlie-kirk-e-baleado-durante-evento-em-universidade.shtml\" target=\"\" rel=\"noopener\">morte do ativista pr\u00f3-Donald Trump, Charlie Kirk,<\/a>\u00a0assassinado durante evento em uma universidade norte-americana. Nos\u00a0<a href=\"https:\/\/www1.folha.uol.com.br\/folha-topicos\/estados-unidos\/\">Estados Unidos<\/a>,\u00a0<a href=\"https:\/\/www1.folha.uol.com.br\/mercado\/2025\/09\/trabalhadores-que-fizeram-posts-sobre-charlie-kirk-sao-demitidos-ou-afastados-nos-eua.shtml\" target=\"\" rel=\"noopener\">empresas dispensaram ou afastaram quem fez postagens<\/a>\u00a0consideradas ofensivas sobre o caso.<\/p>\n<div>\n<div class=\"widget-image rs_skip\">\n<figure>\n<div class=\"c-image-aspect-ratio c-image-aspect-ratio--3x2\"><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive c-image-aspect-ratio__image c-lazyload--loaded aligncenter\" src=\"https:\/\/f.i.uol.com.br\/fotografia\/2025\/09\/16\/175806127068c9e2d6cef83_1758061270_3x2_md.jpg\" alt=\"Um grupo de adultos e crian\u00e7as se re\u00fane em frente a um retrato emoldurado de um homem, que est\u00e1 exposto em um local com paredes de vidro. As pessoas est\u00e3o em um ambiente de homenagem, com velas acesas e flores ao redor. As crian\u00e7as est\u00e3o em destaque, observando o retrato, enquanto os adultos parecem estar confortando umas \u00e0s outras. O cen\u00e1rio \u00e9 iluminado de forma suave, criando uma atmosfera de respeito e lembran\u00e7a.\" width=\"639\" height=\"428\" data-srcset=\" https:\/\/f.i.uol.com.br\/fotografia\/2025\/09\/16\/175806127068c9e2d6cef83_1758061270_3x2_th.jpg 100w,                  https:\/\/f.i.uol.com.br\/fotografia\/2025\/09\/16\/175806127068c9e2d6cef83_1758061270_3x2_xs.jpg 320w,                  https:\/\/f.i.uol.com.br\/fotografia\/2025\/09\/16\/175806127068c9e2d6cef83_1758061270_3x2_sm.jpg 480w,                  https:\/\/f.i.uol.com.br\/fotografia\/2025\/09\/16\/175806127068c9e2d6cef83_1758061270_3x2_md.jpg 768w,                  https:\/\/f.i.uol.com.br\/fotografia\/2025\/09\/16\/175806127068c9e2d6cef83_1758061270_3x2_lg.jpg 1024w,                  https:\/\/f.i.uol.com.br\/fotografia\/2025\/09\/16\/175806127068c9e2d6cef83_1758061270_3x2_xl.jpg 1200w,                  https:\/\/f.i.uol.com.br\/fotografia\/2025\/09\/16\/175806127068c9e2d6cef83_1758061270_3x2_rt.jpg 2400w \" data-sizes=\"(min-width: 1024px) 850px, 100vw\" data-src=\"https:\/\/f.i.uol.com.br\/fotografia\/2025\/09\/16\/175806127068c9e2d6cef83_1758061270_3x2_md.jpg\" \/><\/div><figcaption class=\"widget-image__subtitle\">Pessoas se re\u00fanem no Orem City Center Park, nos Estados Unidos, em memorial pelo ativista e comentarista de direita, Charlie Kirk, morto a tiros &#8211;\u00a0<span class=\"widget-image__credits\">Jim Urquhart\/Reuters<\/span><\/figcaption><\/figure>\n<\/div>\n<\/div>\n<p>No Brasil, a demiss\u00e3o de funcion\u00e1rios considerados extremistas come\u00e7ou a ser incentivada no\u00a0<a href=\"https:\/\/www1.folha.uol.com.br\/folha-topicos\/twitter\/\">Twitter<\/a>\u00a0pelo deputado\u00a0<a href=\"https:\/\/www1.folha.uol.com.br\/folha-topicos\/nikolas-ferreira\/\">Nikolas Ferreira<\/a>\u00a0(PL-MG), e j\u00e1 tem defensores, como o empres\u00e1rio Tallis Gomes, dono do grupo G4 Educa\u00e7\u00e3o.<\/p>\n<div class=\"c-advertising c-advertising--300x250 u-hidden-xs rs_skip\">\n<div id=\"banner-300x250-area-materia\" class=\"c-advertising__banner-area\">\n<div id=\"google_ads_iframe_\/27954005\/folha\/mercado_1__container__\"><\/div>\n<\/div>\n<\/div>\n<p><a href=\"https:\/\/www1.folha.uol.com.br\/mercado\/2025\/09\/um-favor-para-o-brasil-diz-empresario-que-pede-demissao-de-quem-comemora-morte-de-charlie-kirk.shtml\" target=\"\" rel=\"noopener\">Gomes diz que pediu ao setor de recursos humanos para vasculhar as redes de 400 funcion\u00e1rios<\/a>. &#8220;N\u00e3o quero criminoso trabalhando comigo&#8221;, afirmou.<\/p>\n<div id=\"teads0\" class=\"teads-player native\"><\/div>\n<p>Uma contraofensiva da esquerda nas redes sociais alerta trabalhadores sobre as garantias legais quanto \u00e0 liberdade de express\u00e3o, de cren\u00e7a e de posicionamento pol\u00edtico. Segundo postagem compartilhada no Twitter e distribu\u00edda por WhatsApp, a demiss\u00e3o &#8220;por motivos pol\u00edticos \u00e9 crime&#8221; e o funcion\u00e1rio que for v\u00edtima pode entrar com a\u00e7\u00e3o na Justi\u00e7a trabalhista.<\/p>\n<div data-clone-component=\"\">\n<div id=\"infographic-1\" class=\"widget-infographic js-widget-infographic rs_skip\" data-url=\"https:\/\/www1.folha.uol.com.br\/webstories\/cotidiano\/2024\/11\/saiba-quem-e-donald-trump\/\" data-height=\"500\" data-infographic-id=\"infographic-1\"><\/div>\n<\/div>\n<p>Especialistas ouvidos pela\u00a0<strong>Folha\u00a0<\/strong>afirmam que a CLT (Consolida\u00e7\u00e3o das Leis do Trabalho) n\u00e3o tem artigo espec\u00edfico que trate sobre o tema, mas pro\u00edbe pr\u00e1tica discriminat\u00f3ria e, assim como a Constitui\u00e7\u00e3o Federal, garante direito \u00e0 liberdade de express\u00e3o.<\/p>\n<div class=\"player_dynad_tv rs_skip\"><\/div>\n<p>H\u00e1 ainda jurisprud\u00eancia \u2014entendimento consolidado\u2014 do TST (Tribunal Superior do Trabalho) contra dispensa discriminat\u00f3ria e conven\u00e7\u00e3o da OIT (Organiza\u00e7\u00e3o Internacional do Trabalho), da qual o Brasil \u00e9 signat\u00e1rio, que trata da proibi\u00e7\u00e3o de discrimina\u00e7\u00e3o no emprego, abrangendo opini\u00f5es pol\u00edticas.<\/p>\n<p>Esse tipo de demiss\u00e3o, no entanto, n\u00e3o seria considerado crime. O que a lei 9.029 prev\u00ea \u00e9 pris\u00e3o nos casos em que se exigem exames ligados \u00e0 esteriliza\u00e7\u00e3o ou gravidez, diz a advogada Carla Felgueiras, s\u00f3cia do escrit\u00f3rio Montenegro Castelo Advogados Associados.<\/p>\n<div>\n<div id=\"infographic-2\" class=\"widget-infographic js-widget-infographic rs_skip\" data-url=\"https:\/\/www1.folha.uol.com.br\/webstories\/cotidiano\/2021\/06\/qual-seu-perfil-de-trabalho\/\" data-height=\"500\" data-infographic-id=\"infographic-2\"><\/div>\n<\/div>\n<p>Felgueiras afirma que o simples fato de um funcion\u00e1rio expressar opini\u00e3o pol\u00edtica &#8220;de forma razo\u00e1vel e respeitosa&#8221; n\u00e3o pode ser usado como justificativa para dispensa e a empresa tamb\u00e9m n\u00e3o pode exigir ou investigar a orienta\u00e7\u00e3o pol\u00edtica do empregado.<\/p>\n<p>A advogada alerta que se o comportamento do trabalhador ultrapassar os limites do respeito \u2014como associar sua imagem pol\u00edtica \u00e0 da empresa ou prejudicar a imagem institucional\u2014 a situa\u00e7\u00e3o se torna delicada e pode justificar uma demiss\u00e3o por m\u00e1 conduta.<\/p>\n<p>&#8220;O conte\u00fado da manifesta\u00e7\u00e3o pol\u00edtica e o contexto em que ocorre s\u00e3o fundamentais para avaliar a legalidade da dispensa&#8221;, diz ela.<\/p>\n<div>\n<div class=\"c-list c-list--widget rs_skip\">\n<p class=\"c-list__text\"><span style=\"font-size: 29px;font-weight: bold\">DEMISS\u00c3O PRECISA SER JUSTIFICADA?<\/span><\/p>\n<\/div>\n<\/div>\n<p>A advogada Vivian De Camilis, s\u00f3cia da \u00e1rea de Direito do Trabalho do Tilkian Marinelli Marrey Advogados, afirma que o funcion\u00e1rio tem direito \u00e0 liberdade de express\u00e3o nas redes sociais pessoais, desde que fora do ambiente de trabalho.<\/p>\n<div class=\"c-advertising c-advertising--300x250 u-hidden-xs rs_skip\">\n<div id=\"banner-bottom-materia\" class=\"c-advertising__banner-area\"><\/div>\n<\/div>\n<p>Manifesta\u00e7\u00f5es pol\u00edticas feitas na empresa, no hor\u00e1rio de trabalho ou utilizando canais profissionais podem gerar consequ\u00eancias disciplinares que v\u00e3o desde advert\u00eancia at\u00e9 demiss\u00e3o, pr\u00e1tica que ganha for\u00e7a quando h\u00e1 regulamento interno e c\u00f3digo de \u00e9tica e conduta, ou quando a natureza da atividade empresarial exija isen\u00e7\u00e3o por parte de seus profissionais.<\/p>\n<p>As especialistas lembram que, no Brasil, a demiss\u00e3o sem justa causa n\u00e3o precisa ser justificada nem ter uma motiva\u00e7\u00e3o espec\u00edfica. \u00c9 uma prerrogativa do empregador desligar um funcion\u00e1rio, desde que pague os direitos trabalhistas na dispensa.<\/p>\n<div data-clone-component=\"\">\n<div id=\"infographic-3\" class=\"widget-infographic js-widget-infographic rs_skip\" data-url=\"https:\/\/www1.folha.uol.com.br\/webstories\/cotidiano\/2024\/11\/saiba-quem-e-donald-trump\/\" data-height=\"500\" data-infographic-id=\"infographic-3\"><\/div>\n<\/div>\n<h2 id=\"como-provar-que-a-demissao-foi-discriminatoria\" class=\"c-news__subtitle\">COMO PROVAR QUE A DEMISS\u00c3O FOI DISCRIMINAT\u00d3RIA?<\/h2>\n<p>Qualquer demiss\u00e3o discriminat\u00f3ria exige provas por parte do empregado, como documentos e testemunhas, para que se configure o direito \u00e0 reintegra\u00e7\u00e3o ao trabalho ou indeniza\u00e7\u00e3o.<\/p>\n<p>A advogada \u00c9rica Coutinho, do Mauro Menezes &amp; Advogados, diz que se for provado o ass\u00e9dio por orienta\u00e7\u00e3o pol\u00edtica, seja na contrata\u00e7\u00e3o ou na manuten\u00e7\u00e3o do posto de trabalho, tamb\u00e9m \u00e9 poss\u00edvel a condena\u00e7\u00e3o do empregador por danos morais.<\/p>\n<p>&#8220;Esse arcabou\u00e7o foi pensado para proteger os trabalhadores de intimida\u00e7\u00e3o perpetrada por seus empregadores quando h\u00e1 disson\u00e2ncia de posi\u00e7\u00e3o pol\u00edtica&#8221;, diz ela sobre a lei 9.029.<\/p>\n<h2 id=\"qual-o-limite-entre-liberdade-de-expressao-e-postagem-ofensiva\" class=\"c-news__subtitle\">QUAL O LIMITE ENTRE LIBERDADE DE EXPRESS\u00c3O E POSTAGEM OFENSIVA?<\/h2>\n<p>A advogada Priscila Kirchhoff, s\u00f3cia da \u00e1rea trabalhista do Trench Rossi Watanabe, diz que o artigo 5\u00ba da Constitui\u00e7\u00e3o estabelece que &#8220;ningu\u00e9m ser\u00e1 privado de direitos por motivo de cren\u00e7a religiosa ou de convic\u00e7\u00e3o filos\u00f3fica ou pol\u00edtica&#8221;, garantindo a liberdade de express\u00e3o do trabalhador.<\/p>\n<p>Ela refor\u00e7a ainda que, no \u00e2mbito trabalhista, a liberdade de consci\u00eancia, cren\u00e7a e pol\u00edtica \u00e9 crucial, mas que h\u00e1 limites \u00e9ticos, morais e legais.<\/p>\n<p>&#8220;Em outras palavras, a liberdade de express\u00e3o \u00e9 um direito fundamental, mas n\u00e3o \u00e9 absoluto, devendo ser exercido com responsabilidade e sem prejudicar a honra, a privacidade, os direitos alheios ou a atividade empresarial&#8221;, afirma.<\/p>\n<h2 id=\"o-que-o-empregado-deve-fazer\" class=\"c-news__subtitle\">O QUE O EMPREGADO DEVE FAZER?<\/h2>\n<p>&#8220;Postagens relacionadas \u00e0 pol\u00edtica podem levar \u00e0 dispensa do empregado \u2014ou \u00e0 ado\u00e7\u00e3o de outras medidas disciplinares\u2014 quando as suas manifesta\u00e7\u00f5es ultrapassam os limites legais, causando danos, difama\u00e7\u00e3o, cal\u00fania, ou vinculando indevidamente a empresa \u00e0 opini\u00e3o pessoal do trabalhador&#8221;, diz.<\/p>\n<p>Os tribunais tendem, no entanto, a proteger a manifesta\u00e7\u00e3o leg\u00edtima do empregado, desde que n\u00e3o ultrapasse os limites legais.<\/p>\n<div class=\"c-advertising c-advertising--300x250 u-hidden-xs rs_skip\">\n<div id=\"banner-bottom-materia-3\" class=\"c-advertising__banner-area\"><\/div>\n<\/div>\n<p>&#8220;Em caso de postagens pol\u00edticas, recomendamos que o empregado n\u00e3o cite o nome da empresa ou use s\u00edmbolos que a representem. Tamb\u00e9m deve claramente distinguir que se trata de uma opini\u00e3o pessoal, desvinculada das impress\u00f5es do empregador&#8221;, afirma Priscila.<\/p>\n<p>Priscila lembra que trabalhadores que ocupam posi\u00e7\u00e3o de lideran\u00e7a ou t\u00eam cargo de confian\u00e7a precisam tomar ainda mais cuidado.<\/p>\n<h2 id=\"o-que-dizem-as-centrais-sindicais\" class=\"c-news__subtitle\">O QUE DIZEM AS CENTRAIS SINDICAIS?<\/h2>\n<p>Clemente Ganz L\u00facio, presidente do F\u00f3rum das Centrais Sindicais, que re\u00fane todos os sindicatos do pa\u00eds, afirma que as centrais v\u00eam monitorando a situa\u00e7\u00e3o, como fizeram na elei\u00e7\u00e3o, quando houve parceria com o MPT (Minist\u00e9rio P\u00fablico do Trabalho) contra ass\u00e9dio eleitoral, mas acredita que o tema ainda n\u00e3o tomou grandes propor\u00e7\u00f5es no Brasil.<\/p>\n<p>&#8220;Os sindicatos devem agir com cautela, evitando amplificar comportamentos extremistas vindos de indiv\u00edduos isolados&#8221;, diz.<\/p>\n<p>Segundo o sindicalista, nenhum trabalhador pode ser demitido por posicionamento pol\u00edtico, seja por apoiar determinado candidato, ser filiado a um partido ou ser membro de sindicato, mas h\u00e1 pr\u00e1ticas que justificariam uma demiss\u00e3o \u2014at\u00e9 mesmo por justa causa\u2014 e, por isso, \u00e9 preciso ter cuidado.<\/p>\n<div class=\"c-advertising c-advertising--300x250 u-hidden-xs rs_skip\">\n<div id=\"banner-bottom-materia-4\" class=\"c-advertising__banner-area\"><\/div>\n<\/div>\n<p>Dentre as a\u00e7\u00f5es est\u00e3o atos que prejudiquem a imagem da empresa, que possam ser considerados crimes, ou que ofendam a honra de pessoas ou organiza\u00e7\u00f5es.<\/p>\n<div>\n<div class=\"c-video js-widget-youtube widget-youtube rs_skip\" data-video=\"\" data-href=\"https:\/\/www.youtube.com\/watch?v=Sm1dFTADnx0\">\n<div class=\"c-video__container\" data-video-container=\"\"><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Lei brasileira pro\u00edbe demiss\u00e3o discriminat\u00f3ria, e trabalhador pode ter indeniza\u00e7\u00e3o ou ser reintegrado. Empregador n\u00e3o precisa justificar motivo e pode dispensar colaborador caso conduta incite viol\u00eancia<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[44],"tags":[],"class_list":["post-118791","post","type-post","status-publish","format-standard","hentry","category-shopping-patio-higienopolis"],"acf":[],"_links":{"self":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts\/118791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=118791"}],"version-history":[{"count":1,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts\/118791\/revisions"}],"predecessor-version":[{"id":118792,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts\/118791\/revisions\/118792"}],"wp:attachment":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=118791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=118791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=118791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}