{"id":118705,"date":"2025-09-15T08:49:09","date_gmt":"2025-09-15T11:49:09","guid":{"rendered":"https:\/\/monitoramento.spmj.com.br\/noticias\/?p=118705"},"modified":"2025-09-15T08:49:09","modified_gmt":"2025-09-15T11:49:09","slug":"governadores-participam-de-evento-sobre-mercado-de-luxo-no-interior-de-sao-paulo","status":"publish","type":"post","link":"https:\/\/monitoramento.spmj.com.br\/noticias\/2025\/09\/15\/governadores-participam-de-evento-sobre-mercado-de-luxo-no-interior-de-sao-paulo\/","title":{"rendered":"Governadores participam de evento sobre mercado de luxo no interior de S\u00e3o Paulo"},"content":{"rendered":"<section class=\"content--header\">\n<div class=\"row medium-uncollapsed content-top-image\" data-block-type=\"featured-image\" data-block-id=\"0\">\n<div class=\"column medium-centered medium-22 large-20 desktop \">\n<figure class=\"content-featured-figure\"><img loading=\"lazy\" decoding=\"async\" class=\"content-featured-image\" src=\"https:\/\/s2-cbn.glbimg.com\/CpKQxp_Ldt_ezfjOsXKjZTioTt0=\/494x0:1920x1080\/888x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_d975fad146a14bbfad9e763717b09688\/internal_photos\/bs\/2025\/j\/Q\/ASi39BRhaCfXDsGfBhKw\/site-template-grade-de-fotos-2025-08-25t181910.172.png\" alt=\"Governadores Romeu Zema, de Minas Gerais; Ronaldo Caiado, de Goi\u00e1s; e Ratinho J\u00fanior, do Paran\u00e1\" width=\"1426\" height=\"1080\" \/><figcaption class=\"content-featured-caption\">Governadores Romeu Zema, de Minas Gerais; Ronaldo Caiado, de Goi\u00e1s; e Ratinho J\u00fanior, do Paran\u00e1 \u2014 Foto: Pablo Jacob\/Governo do Estado de SP; Marcelo Camargo\/Ag\u00eancia Brasil; Antonio Cruz\/ Ag\u00eancia Brasil; Alan Santos\/PR<\/figcaption><\/figure>\n<\/div>\n<\/div>\n<\/section>\n<div id=\"mc-article-body\" class=\"mc-article-body \">\n<article>\n<div class=\"no-paywall\">\n<div class=\"mc-column mc-side-item__container\" data-block-type=\"ads\" data-block-id=\"1\">\n<div class=\"mc-side-item mc-side-item--right content-ads content-ads--side-ad mc-side-item-block\">\n<div id=\"banner_materia1\" class=\"tag-manager-publicidade-container tag-manager-publicidade-banner_materia1 tag-manager-publicidade-container--carregado tag-manager-publicidade-container--visivel\" data-google-query-id=\"CLTa5pHZ2o8DFV5puAQde_MFlA\">\n<div id=\"google_ads_iframe_\/85042905\/cbn\/sao-paulo_1__container__\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles active-capital-letter\" data-block-type=\"unstyled\" data-block-weight=\"45\" data-block-id=\"2\">\n<p class=\" content-text__container theme-color-primary-first-letter\" data-track-category=\"Link no Texto\" data-track-links=\"\">Os governadores de Goias, Ronaldo Caiado, do Uni\u00e3o Brasil; de Minas Gerais, Romeu Zema, do Novo; e do Paran\u00e1, Ratinho J\u00fanior, do PSD, participam neste s\u00e1bado de um evento sobre o mercado de luxo patrocinado por grandes grifes, em Itu, no interior do estado.<\/p>\n<\/div>\n<div class=\"wall protected-content\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"21\" data-block-id=\"3\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Os presidenci\u00e1veis que disputam o esp\u00f3lio eleitoral de Jair Bolsonaro v\u00e3o fazer uma palestra de uma hora durante um painel.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"30\" data-block-id=\"4\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">No mesmo dia, outro painel tamb\u00e9m re\u00fane o presidente do PSD e secret\u00e1rio estadual de Rela\u00e7\u00f5es Institucionais de S\u00e3o Paulo, Gilberto Kassab, e o presidente do PP, Ciro Nogueira.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"15\" data-block-id=\"5\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">O governador de S\u00e3o Paulo, Tarc\u00edsio de Freitas, n\u00e3o participa do evento neste s\u00e1bado.<\/p>\n<\/div>\n<div id=\"pub-in-text-wrapper\">\n<div id=\"pub-in-text\" class=\"tag-manager-publicidade-container tag-manager-publicidade-pub-in-text tag-manager-publicidade-container--carregado tag-manager-publicidade-container--visivel\" data-google-query-id=\"CPHrpavZ2o8DFUJbuAQdGCYVdg\">\n<div id=\"google_ads_iframe_\/85042905\/cbn\/sao-paulo_4__container__\"><\/div>\n<\/div>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"26\" data-block-id=\"6\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">No entanto, ele deve embarcar para Bras\u00edlia na pr\u00f3xima segunda-feira para apoiar a articula\u00e7\u00e3o do projeto de anistia com o presidente da C\u00e2mara, Hugo Motta.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"17\" data-block-id=\"7\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Poss\u00edvel presidenci\u00e1vel para as elei\u00e7\u00f5es de 2026, ele seguir\u00e1 dedicado para a mat\u00e9ria avance no Congresso Nacional.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"28\" data-block-id=\"8\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">De acordo com um levantamento da CBN, os governadores de direita intensificaram as agendas nacionais este ano na tentativa de projetar os nomes para al\u00e9m dos pr\u00f3prios estados.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"13\" data-block-id=\"9\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Dois desses governadores estiveram reunidos em eventos em pelo menos 13 oportunidades.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"18\" data-block-id=\"10\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">A \u00faltima vez em que isso aconteceu foi no fim do m\u00eas de agosto, tamb\u00e9m em S\u00e3o Paulo.<\/p>\n<\/div>\n<div data-track-category=\"multicontent\" data-track-action=\"ultimo chunk conteudo\" data-track-noninteraction=\"false\" data-track-scroll=\"view\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"24\" data-block-id=\"11\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">No m\u00eas passado, o governador de Minas Gerais, Romeu Zema lan\u00e7ou a pr\u00e9-candidatura dele \u00e0 presid\u00eancia pleo Partido Novo num evento na capital paulista.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Os governadores de Goias, Ronaldo Caiado, do Uni\u00e3o Brasil; de Minas Gerais, Romeu Zema, do Novo; e do Paran\u00e1, Ratinho J\u00fanior, do PSD, participam neste s\u00e1bado de um evento sobre o mercado de luxo patrocinado por grandes grifes, em Itu, no interior do estado.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[44],"tags":[],"class_list":["post-118705","post","type-post","status-publish","format-standard","hentry","category-shopping-patio-higienopolis"],"acf":[],"_links":{"self":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts\/118705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=118705"}],"version-history":[{"count":1,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts\/118705\/revisions"}],"predecessor-version":[{"id":118706,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts\/118705\/revisions\/118706"}],"wp:attachment":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=118705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=118705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=118705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}