{"id":118535,"date":"2025-09-09T08:49:25","date_gmt":"2025-09-09T11:49:25","guid":{"rendered":"https:\/\/monitoramento.spmj.com.br\/noticias\/?p=118535"},"modified":"2025-09-09T08:49:25","modified_gmt":"2025-09-09T11:49:25","slug":"itau-demite-cerca-de-mil-funcionarios-por-baixa-produtividade-no-trabalho-remoto","status":"publish","type":"post","link":"https:\/\/monitoramento.spmj.com.br\/noticias\/2025\/09\/09\/itau-demite-cerca-de-mil-funcionarios-por-baixa-produtividade-no-trabalho-remoto\/","title":{"rendered":"Ita\u00fa demite cerca de mil funcion\u00e1rios por baixa produtividade no trabalho remoto"},"content":{"rendered":"<p class=\"styles__ParagraphStyled-sc-6adecn-0 cWrRiu  \" data-component-name=\"paragraph\">O\u00a0<a title=\"https:\/\/www.estadao.com.br\/tudo-sobre\/itau-banco\/\" href=\"https:\/\/www.estadao.com.br\/tudo-sobre\/itau-banco\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Ita\u00fa Unibanco<\/strong><\/a> demitiu nesta segunda-feira, 8, cerca de mil funcion\u00e1rios, principalmente aqueles com trabalho remoto, com a justificativa de baixa produtividade. Nas redes sociais, foram v\u00e1rios relatos ao longo do dia. A informa\u00e7\u00e3o sobre o n\u00famero de desligamentos \u00e9 do Sindicato dos Banc\u00e1rios de S\u00e3o Paulo, Osasco e Regi\u00e3o, que divulgou comunicado nesta segunda \u201crepudiando as demiss\u00f5es\u201d do banco.<\/p>\n<div class=\"styles__MultiParagraphAdStyled-sc-1yb8ue6-0 gJoYAt\" data-component-name=\"multi-paragraph\">\n<div class=\" ads-container\">\n<div class=\"styles__Container-sc-1v8tg5g-0 kdBSPY\">\n<div class=\"ads-placeholder-wrapper\">\n<div id=\"tmeio1-2\" class=\"styles__AdSlotStyled-sc-1l64tzh-0 eotsDo formato-tmeio1\" data-google-query-id=\"COmMjeXNy48DFV5c3QIdL6kJJQ\">\n<div id=\"google_ads_iframe_\/118650305\/economia\/noticia_1__container__\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"paragraph\">\n<p>O Ita\u00fa confirmou que houve desligamentos em nota ao\u00a0<em>Estad\u00e3o\/Broadcast<\/em>, mas ressaltou que ocorreram ap\u00f3s \u201crevis\u00e3o criteriosa\u201d de condutas relacionadas ao trabalho remoto, de forma individual. O banco n\u00e3o citou o n\u00famero de cortes, mas diz que n\u00e3o ocorreu demiss\u00e3o em massa ou layoff.<\/p>\n<p>\u201cO Ita\u00fa Unibanco realizou hoje\u00a0<em>(segunda, 8)\u00a0<\/em>desligamentos decorrentes de uma revis\u00e3o criteriosa de condutas relacionadas ao trabalho remoto e registro de jornada.\u201d<\/p>\n<\/div>\n<\/div>\n<figure class=\"styles__FigureImageWrapper-sc-1qk1vbn-0 NaVlt figure-image-wrapper   \">\n<div class=\"figure-image-container\"><button class=\"expandir imagem\"><\/button><img decoding=\"async\" src=\"https:\/\/www.estadao.com.br\/resizer\/v2\/GPT2SUB7YJDSJDCNXT2BIIY3RA.jpg?quality=80&amp;auth=ddd6a7ccb2c29b593adb35c07d5d18b318ca45638b1eaef3df78252a0506a0e8&amp;width=380\" alt=\"Ita\u00fa tem 85,8 mil funcion\u00e1rios no Brasil\" data-srcset=\"https:\/\/www.estadao.com.br\/resizer\/v2\/GPT2SUB7YJDSJDCNXT2BIIY3RA.jpg?quality=80&amp;auth=ddd6a7ccb2c29b593adb35c07d5d18b318ca45638b1eaef3df78252a0506a0e8&amp;width=380 768w, https:\/\/www.estadao.com.br\/resizer\/v2\/GPT2SUB7YJDSJDCNXT2BIIY3RA.jpg?quality=80&amp;auth=ddd6a7ccb2c29b593adb35c07d5d18b318ca45638b1eaef3df78252a0506a0e8&amp;width=768 1024w, https:\/\/www.estadao.com.br\/resizer\/v2\/GPT2SUB7YJDSJDCNXT2BIIY3RA.jpg?quality=80&amp;auth=ddd6a7ccb2c29b593adb35c07d5d18b318ca45638b1eaef3df78252a0506a0e8&amp;width=1200 1322w\" \/><\/div><figcaption class=\"ignore-change-font-for-app\">\n<div class=\"\">Ita\u00fa tem 85,8 mil funcion\u00e1rios no Brasil Foto: Werther Santana\/Estad\u00e3o<\/div>\n<\/figcaption><\/figure>\n<p class=\"styles__ParagraphStyled-sc-6adecn-0 cWrRiu  \" data-component-name=\"paragraph\">Segundo o banco, \u201cem alguns casos, foram identificados padr\u00f5es incompat\u00edveis com nossos princ\u00edpios de confian\u00e7a, que s\u00e3o inegoci\u00e1veis para o banco\u201d. \u201cEssas decis\u00f5es fazem parte de um processo de gest\u00e3o respons\u00e1vel e t\u00eam como objetivo preservar nossa cultura e a rela\u00e7\u00e3o de confian\u00e7a que constru\u00edmos com clientes, colaboradores e a sociedade\u201d, afirma a nota do Ita\u00fa.<\/p>\n<p class=\"styles__ParagraphStyled-sc-6adecn-0 cWrRiu  \" data-component-name=\"paragraph\">Segundo o sindicato, a \u201cjustificativa do banco foi que os empregados estavam sendo monitorados h\u00e1 mais de seis meses e foi detectada \u2018baixa ader\u00eancia ao home office\u2019\u201d. A entidade diz que os \u201ctrabalhadores foram dispensados sem qualquer advert\u00eancia pr\u00e9via e sem qualquer di\u00e1logo com o sindicato\u201d.<\/p>\n<p class=\"styles__ParagraphStyled-sc-6adecn-0 cWrRiu  \" data-component-name=\"paragraph\">\u201cHoje, fomos surpreendidos com essa demiss\u00e3o em massa feita pelo banco. O banco afirma que os desligamentos se baseiam em registros de inatividade nas m\u00e1quinas corporativas, em alguns casos, per\u00edodos de quatro horas ou mais de suposta ociosidade\u201d, afirma o diretor do sindicato e banc\u00e1rio do Ita\u00fa, Maikon Azzi, em nota.<\/p>\n<div class=\"styles__Container-sc-1kqto0p-0 eruJko\" title=\"Economia &amp; Neg\u00f3cios\">\n<div class=\"warning\">Ao se cadastrar nas newsletters, voc\u00ea concorda com os\u00a0<a href=\"https:\/\/www.estadao.com.br\/termo-de-uso\">Termos de Uso<\/a>\u00a0e\u00a0<a href=\"https:\/\/www.estadao.com.br\/termo-de-uso#politica-privacidade\">Pol\u00edtica de Privacidade<\/a>.<\/div>\n<\/div>\n<p class=\"styles__ParagraphStyled-sc-6adecn-0 cWrRiu  \" data-component-name=\"paragraph\">Nas redes sociais, foram v\u00e1rios coment\u00e1rios. \u201cEu achei estranho essa demiss\u00e3o em massa de muitos desenvolvedores do banco do Ita\u00fa\u201d, escreveu um usu\u00e1rio no X. \u201cDemiss\u00e3o em massa no Ita\u00fa Unibanco\u201d, escreveu outro. Nas mensagens, relatos variavam de mil a 5 mil cortes.<\/p>\n<p class=\"styles__ParagraphStyled-sc-6adecn-0 cWrRiu  \" data-component-name=\"paragraph\">\u201c\u00c9 inaceit\u00e1vel que uma institui\u00e7\u00e3o que registra lucros bilion\u00e1rios promova demiss\u00f5es em massa sob a justificativa de \u2018produtividade\u2019. Os avan\u00e7os tecnol\u00f3gicos e os ganhos decorrentes da digitaliza\u00e7\u00e3o poderiam ser revertidos em melhores condi\u00e7\u00f5es de trabalho e em emprego decente\u201d, afirma a nota do sindicato dos banc\u00e1rios.<\/p>\n<div class=\" ads-container\">\n<div class=\"styles__Container-sc-1v8tg5g-0 cZpEMP\">\n<div class=\"ads-placeholder-wrapper\">\n<div id=\"hmeio2-4\" class=\"styles__AdSlotStyled-sc-1l64tzh-0 eotsDo formato-hmeio2\" data-google-query-id=\"CIKvxpzOy48DFats3QIdo6kKZQ\">\n<div id=\"google_ads_iframe_\/118650305\/economia\/noticia_3__container__\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p class=\"styles__ParagraphStyled-sc-6adecn-0 cWrRiu  \" data-component-name=\"paragraph\">Ao todo, o Ita\u00fa tem 95,7 mil funcion\u00e1rios aqui e nos pa\u00edses onde opera. Desse total, 85,8 mil s\u00e3o s\u00f3 no Brasil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Banco confirmou desligamentos, mas ressaltou que eles ocorreram ap\u00f3s \u2018revis\u00e3o criteriosa\u2019 de condutas no trabalho remoto; n\u00famero de demiss\u00f5es foi divulgado por sindicato<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[44],"tags":[],"class_list":["post-118535","post","type-post","status-publish","format-standard","hentry","category-shopping-patio-higienopolis"],"acf":[],"_links":{"self":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts\/118535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=118535"}],"version-history":[{"count":1,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts\/118535\/revisions"}],"predecessor-version":[{"id":118536,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts\/118535\/revisions\/118536"}],"wp:attachment":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=118535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=118535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=118535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}