{"id":114915,"date":"2025-06-05T13:21:57","date_gmt":"2025-06-05T16:21:57","guid":{"rendered":"https:\/\/monitoramento.spmj.com.br\/noticias\/?p=114915"},"modified":"2025-06-05T13:21:57","modified_gmt":"2025-06-05T16:21:57","slug":"amazon-testa-robos-humanoides-para-substituir-entregadores-humanos","status":"publish","type":"post","link":"https:\/\/monitoramento.spmj.com.br\/noticias\/2025\/06\/05\/amazon-testa-robos-humanoides-para-substituir-entregadores-humanos\/","title":{"rendered":"Amazon testa rob\u00f4s humanoides para substituir entregadores humanos"},"content":{"rendered":"<div data-js=\"hero-container\">\n<div class=\"mb-7 mt-2 flex w-full flex-col gap-2\">\n<h2 class=\"m-0 p-0 text-colors-text xl:text-pretty title-medium dark:text-colors-background\">Gigante do varejo desenvolve rob\u00f4s para fazer entregas em casas, partindo de vans el\u00e9tricas Rivian, segundo o site The Information<\/h2>\n<\/div>\n<\/div>\n<div class=\"my-6 w-full lg:my-7\">\n<div class=\"mb-2 flex gap-2\">\n<figure class=\"relative flex items-center justify-center overflow-hidden rounded-full bg-colors-exame90 object-cover text-colors-background w-7 h-7\">&lt;img src=&quot;data:;base64,&#8221; alt=&#8221;&#8221; aria-hidden=&#8221;true&#8221; \/&gt;<img decoding=\"async\" class=\"object-cover\" src=\"https:\/\/12ft.io\/api\/proxy?q=https%3A%2F%2Fexame.com%2Finteligencia-artificial%2Famazon-testa-robos-humanoides-para-substituir-entregadores-humanos%2F\" alt=\"Tamires Vitorio\" data-nimg=\"intrinsic\" \/><\/figure>\n<div class=\"flex flex-col\"><a class=\"m-0 p-0 text-colors-text xl:text-pretty label-small hover:underline\" href=\"https:\/\/12ft.io\/proxy?q=https%3A%2F%2Fexame.com%2Fautor%2Ftamires-vitorio\" target=\"_parent\" rel=\"noopener\">Tamires Vitorio<\/a><\/p>\n<p class=\"m-0 p-0 text-colors-text xl:text-pretty title-extra-small\">Rep\u00f3rter<\/p>\n<\/div>\n<\/div>\n<p class=\"m-0 p-0 text-colors-text xl:text-pretty body-small\">Publicado em\u00a05 de junho de 2025 \u00e0s06h59.<\/p>\n<\/div>\n<div>\n<section class=\"relative grid gap-6\">\n<div class=\"flex justify-between items-center py-4 border border-solid border-colors-divider dark:border-colors-dark-divider border-x-0\">\n<div><span class=\"m-0 p-0 text-colors-text xl:text-pretty headline-extra-small mr-1 hidden lg:inline-block dark:text-colors-background\">Acompanhe tudo sobre<\/span><span class=\"m-0 p-0 text-colors-text xl:text-pretty headline-extra-small inline dark:text-colors-background\">Amazon<\/span><\/div>\n<p><a class=\"items-center rounded-6 cursor-pointer flex justify-center py-3 px-6 border-solid border no-underline transition-all ease-in select-none bg-colors-background border-colors-divider [&amp;&gt;span]:text-colors-primary hover:bg-colors-exame10 active:border-colors-primary\" href=\"https:\/\/12ft.io\/proxy?q=https%3A%2F%2Fexame.com%2Farquivo%2Famazon%2F\" target=\"_parent\" rel=\"noopener\"><span class=\"m-0 p-0 text-colors-text xl:text-pretty label-large whitespace-nowrap\">Saiba mais<\/span><\/a><\/div>\n<div class=\"section-item relative w-full\">\n<div id=\"news-body\" class=\"relative grid\">\n<p class=\"m-0 p-0 xl:text-pretty body-extra-large overflow-hidden py-3 text-colors-text dark:text-colors-background lg:py-4\">A\u00a0<strong>Amazon (AMZN)<\/strong>\u00a0est\u00e1 dando passos importantes no desenvolvimento de rob\u00f4s humanoides que t\u00eam o potencial de transformar a entrega de pacotes feitas por humanos, segundo o site\u00a0<em>The Information<\/em>.<\/p>\n<article class=\"text-token-text-primary w-full\" dir=\"auto\" data-testid=\"conversation-turn-16\" data-scroll-anchor=\"true\">\n<div class=\"text-base my-auto mx-auto py-5 [--thread-content-margin:--spacing(4)] @[37rem]:[--thread-content-margin:--spacing(6)] @[72rem]:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:32rem] @[34rem]:[--thread-content-max-width:40rem] @[64rem]:[--thread-content-max-width:48rem] mx-auto flex max-w-(--thread-content-max-width) flex-1 text-base gap-4 md:gap-5 lg:gap-6 group\/turn-messages focus-visible:outline-hidden\">\n<div class=\"group\/conversation-turn relative flex w-full min-w-0 flex-col agent-turn\">\n<div class=\"relative flex-col gap-1 md:gap-3\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-5\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"60c3aa59-fc6c-4206-acd0-0ac6fd08c35c\" data-message-model-slug=\"gpt-4o-mini\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\">\n<div class=\"markdown prose dark:prose-invert w-full break-words light\">\n<p class=\"m-0 p-0 xl:text-pretty body-extra-large overflow-hidden py-3 text-colors-text dark:text-colors-background lg:py-4\">Os rob\u00f4s humanoides da Amazon, ainda em fases iniciais de desenvolvimento e testes, est\u00e3o sendo avaliados em ambientes controlados, como o chamado \u201cparque humanoide\u201d, um espa\u00e7o projetado para simular condi\u00e7\u00f5es reais de entrega. Nesse ambiente, os rob\u00f4s enfrentam desafios como obst\u00e1culos, escadas e outras situa\u00e7\u00f5es comuns durante a entrega de pacotes.<\/p>\n<p class=\"m-0 p-0 xl:text-pretty body-extra-large overflow-hidden py-3 text-colors-text dark:text-colors-background lg:py-4\">Um dos modelos em teste, o\u00a0<strong>Unitree G1<\/strong>, por exemplo, tem a capacidade de subir escadas e carregar pacotes, mas sua implementa\u00e7\u00e3o em um cen\u00e1rio de entrega real, fora do ambiente controlado, ainda n\u00e3o est\u00e1 pronta para ocorrer.<\/p>\n<p class=\"m-0 p-0 xl:text-pretty body-extra-large overflow-hidden py-3 text-colors-text dark:text-colors-background lg:py-4\">Apesar dos avan\u00e7os na tecnologia, a Amazon esclareceu que,\u00a0<span class=\"is_emphasis\">neste momento, o principal objetivo dos rob\u00f4s \u00e9 complementar, e n\u00e3o substituir, os entregadores humanos<\/span>.<\/p>\n<p class=\"m-0 p-0 xl:text-pretty body-extra-large overflow-hidden py-3 text-colors-text dark:text-colors-background lg:py-4\">A empresa est\u00e1 desenvolvendo um software especializado em\u00a0<strong>intelig\u00eancia artificial<\/strong>\u00a0para permitir que esses rob\u00f4s executem tarefas mais complexas, como navegar de forma aut\u00f4noma por ambientes imprevis\u00edveis, interagir com os clientes e responder a comandos de voz.<\/p>\n<p class=\"m-0 p-0 xl:text-pretty body-extra-large overflow-hidden py-3 text-colors-text dark:text-colors-background lg:py-4\">Os testes iniciais s\u00e3o essenciais para avaliar se os rob\u00f4s humanoides podem operar de forma eficaz e segura no mundo real, antes de serem integrados definitivamente \u00e0 cadeia log\u00edstica da Amazon.<\/p>\n<p class=\"m-0 p-0 xl:text-pretty body-extra-large overflow-hidden py-3 text-colors-text dark:text-colors-background lg:py-4\">At\u00e9 que a tecnologia se prove plenamente funcional, os rob\u00f4s trabalhar\u00e3o ao lado dos humanos, atuando como uma ferramenta que amplia a efici\u00eancia do trabalho realizado por entregadores, segundo o\u00a0<em>The Information<\/em>.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<h2 class=\"m-0 p-0 xl:text-pretty headline-small py-3 text-colors-text dark:text-colors-background\">Como funciona o atual modelo de entregas da Amazon<\/h2>\n<p class=\"m-0 p-0 xl:text-pretty body-extra-large overflow-hidden py-3 text-colors-text dark:text-colors-background lg:py-4\">Atualmente, a Amazon conta com uma rede global de mais de\u00a0<strong>275 mil motoristas de entrega<\/strong>, respons\u00e1veis por entregar mais de\u00a0<strong>10 milh\u00f5es de pacotes<\/strong>\u00a0todos os dias.<\/p>\n<p class=\"m-0 p-0 xl:text-pretty body-extra-large overflow-hidden py-3 text-colors-text dark:text-colors-background lg:py-4\">Esses motoristas operam principalmente atrav\u00e9s dos\u00a0<strong>Delivery Service Partners (DSPs)<\/strong>, que s\u00e3o empresas parceiras da Amazon. A Amazon tem mais de\u00a0<strong>3.000 DSPs<\/strong>\u00a0ao redor do mundo, que empregam, em m\u00e9dia, at\u00e9\u00a0<strong>100 pessoas<\/strong>\u00a0e gerenciam entre\u00a0<strong>20 e 40 vans<\/strong>\u00a0da Amazon cada uma.<\/p>\n<h2 class=\"m-0 p-0 xl:text-pretty headline-small py-3 text-colors-text dark:text-colors-background\">A evolu\u00e7\u00e3o da intelig\u00eancia artificial e o papel dos rob\u00f4s humanoides<\/h2>\n<p class=\"m-0 p-0 xl:text-pretty body-extra-large overflow-hidden py-3 text-colors-text dark:text-colors-background lg:py-4\">Com o desenvolvimento de sua pr\u00f3pria\u00a0<strong>intelig\u00eancia artificial<\/strong>, a Amazon est\u00e1 criando solu\u00e7\u00f5es tecnol\u00f3gicas para aprimorar suas opera\u00e7\u00f5es log\u00edsticas, como os rob\u00f4s humanoides para entregas.<\/p>\n<p class=\"m-0 p-0 xl:text-pretty body-extra-large overflow-hidden py-3 text-colors-text dark:text-colors-background lg:py-4\"><span class=\"is_emphasis\">O objetivo da empresa \u00e9 utilizar esses rob\u00f4s para realizar tarefas de &#8220;<strong>\u00faltima milha<\/strong>&#8220;, que envolvem a entrega do pacote da van at\u00e9 a porta do cliente<\/span>. Para isso, os rob\u00f4s ser\u00e3o projetados para operar de forma aut\u00f4noma, sem a necessidade de interven\u00e7\u00e3o humana durante esse processo.<\/p>\n<h2 class=\"m-0 p-0 xl:text-pretty headline-small py-3 text-colors-text dark:text-colors-background\">Desafios t\u00e9cnicos e regulat\u00f3rios<\/h2>\n<p class=\"m-0 p-0 xl:text-pretty body-extra-large overflow-hidden py-3 text-colors-text dark:text-colors-background lg:py-4\">Embora os rob\u00f4s humanoides sejam promissores, ainda existem muitos desafios pela frente. O principal deles envolve os obst\u00e1culos t\u00e9cnicos relacionados \u00e0 capacidade dos rob\u00f4s de realizar entregas em um mundo real, onde o terreno pode ser irregular e imprevis\u00edvel.<\/p>\n<p class=\"m-0 p-0 xl:text-pretty body-extra-large overflow-hidden py-3 text-colors-text dark:text-colors-background lg:py-4\">Al\u00e9m disso, as quest\u00f5es regulat\u00f3rias tamb\u00e9m devem ser enfrentadas, j\u00e1 que a implementa\u00e7\u00e3o em larga escala de rob\u00f4s de entrega pode exigir mudan\u00e7as nas leis de tr\u00e2nsito e nas regulamenta\u00e7\u00f5es de seguran\u00e7a.<\/p>\n<p class=\"m-0 p-0 xl:text-pretty body-extra-large overflow-hidden py-3 text-colors-text dark:text-colors-background lg:py-4\">A Amazon tamb\u00e9m est\u00e1 ciente de que, por enquanto, os rob\u00f4s n\u00e3o ser\u00e3o capazes de lidar com todos os tipos de situa\u00e7\u00f5es que um\u00a0<strong>entregador humano<\/strong>\u00a0pode resolver. Em muitos casos, \u00e9 necess\u00e1rio o discernimento humano para tomar decis\u00f5es r\u00e1pidas e eficazes diante de imprevistos. Por isso, a empresa enfatiza que, no curto prazo, os rob\u00f4s humanoides ser\u00e3o usados para complementar os trabalhadores humanos, n\u00e3o para substitu\u00ed-los.<\/p>\n<h2 class=\"m-0 p-0 xl:text-pretty headline-small py-3 text-colors-text dark:text-colors-background\">Um bom momento para a Amazon<\/h2>\n<p class=\"m-0 p-0 xl:text-pretty body-extra-large overflow-hidden py-3 text-colors-text dark:text-colors-background lg:py-4\">No primeiro trimestre de 2025, a Amazon obteve\u00a0<strong data-start=\"47\" data-end=\"68\">US$ 155,7 bilh\u00f5es<\/strong>\u00a0em vendas l\u00edquidas, o que representa um aumento de\u00a0<strong data-start=\"120\" data-end=\"126\">9%<\/strong>\u00a0em compara\u00e7\u00e3o com o mesmo per\u00edodo de 2024. Esse desempenho foi impulsionado pelo crescimento nas vendas da\u00a0<strong data-start=\"234\" data-end=\"254\">Am\u00e9rica do Norte<\/strong>, que subiram\u00a0<strong data-start=\"268\" data-end=\"274\">8%<\/strong>, totalizando\u00a0<strong data-start=\"288\" data-end=\"308\">US$ 92,9 bilh\u00f5es<\/strong>, al\u00e9m de um aumento de\u00a0<strong data-start=\"332\" data-end=\"339\">19%<\/strong>\u00a0na receita com publicidade, que atingiu\u00a0<strong data-start=\"380\" data-end=\"400\">US$ 13,9 bilh\u00f5es<\/strong>. O servi\u00e7o de nuvem da Amazon, o\u00a0<strong data-start=\"434\" data-end=\"463\">Amazon Web Services (AWS)<\/strong>, tamb\u00e9m contribuiu com\u00a0<strong data-start=\"487\" data-end=\"507\">US$ 29,3 bilh\u00f5es<\/strong>\u00a0em receita, um crescimento de\u00a0<strong data-start=\"538\" data-end=\"545\">17%<\/strong>\u00a0em rela\u00e7\u00e3o ao ano anterior.<\/p>\n<p class=\"m-0 p-0 xl:text-pretty body-extra-large overflow-hidden py-3 text-colors-text dark:text-colors-background lg:py-4\">Esses resultados financeiros positivos refletem o cont\u00ednuo dom\u00ednio da Amazon nos setores de\u00a0<strong data-start=\"667\" data-end=\"681\">e-commerce<\/strong>,\u00a0<strong data-start=\"683\" data-end=\"706\">computa\u00e7\u00e3o em nuvem<\/strong>\u00a0e\u00a0<strong data-start=\"709\" data-end=\"736\">intelig\u00eancia artificial<\/strong>. Em 2025, grandes bancos t\u00eam uma vis\u00e3o predominantemente otimista em rela\u00e7\u00e3o ao futuro da Amazon, destacando sua lideran\u00e7a em\u00a0<strong data-start=\"863\" data-end=\"882\">cloud computing<\/strong>,\u00a0<strong data-start=\"884\" data-end=\"890\">IA<\/strong>\u00a0e e-commerce, ao mesmo tempo que reconhecem alguns riscos associados \u00e0 concorr\u00eancia e \u00e0 regulamenta\u00e7\u00e3o.<\/p>\n<p class=\"m-0 p-0 xl:text-pretty body-extra-large overflow-hidden py-3 text-colors-text dark:text-colors-background lg:py-4\">O\u00a0<strong data-start=\"998\" data-end=\"1024\">Bank of America (BofA)<\/strong>, em particular, tem uma vis\u00e3o extremamente positiva sobre as perspectivas de crescimento da Amazon, especialmente impulsionadas pelo AWS. O banco prev\u00ea um crescimento de\u00a0<strong data-start=\"1195\" data-end=\"1202\">25%<\/strong>\u00a0na receita do AWS em 2025, o que pode levar a receita do segmento a se aproximar dos\u00a0<strong data-start=\"1288\" data-end=\"1307\">US$ 100 bilh\u00f5es<\/strong>. O BofA destaca que a Amazon det\u00e9m cerca de\u00a0<strong data-start=\"1352\" data-end=\"1359\">40%<\/strong>\u00a0do gasto global com infraestrutura de nuvem e v\u00ea o AWS como um motor de crescimento de\u00a0<strong data-start=\"1447\" data-end=\"1464\">margens altas<\/strong>, superando concorrentes como\u00a0<strong data-start=\"1494\" data-end=\"1513\">Microsoft Azure<\/strong>\u00a0e\u00a0<strong data-start=\"1516\" data-end=\"1532\">Google Cloud<\/strong>.<\/p>\n<p class=\"m-0 p-0 xl:text-pretty body-extra-large overflow-hidden py-3 text-colors-text dark:text-colors-background lg:py-4\">Al\u00e9m disso, o BofA aponta para a base de assinantes do\u00a0<strong data-start=\"1590\" data-end=\"1606\">Amazon Prime<\/strong>\u00a0(mais de\u00a0<strong data-start=\"1616\" data-end=\"1631\">250 milh\u00f5es<\/strong>\u00a0de assinantes) e para o segmento de publicidade da empresa, que deve crescer\u00a0<strong data-start=\"1709\" data-end=\"1716\">20%<\/strong>\u00a0ao ano e ultrapassar\u00a0<strong data-start=\"1738\" data-end=\"1756\">US$ 50 bilh\u00f5es<\/strong>\u00a0em 2025, como pilares-chave para apoiar a diversifica\u00e7\u00e3o e expans\u00e3o da receita da Amazon. O banco elevou a meta de pre\u00e7o para as a\u00e7\u00f5es da Amazon para\u00a0<strong data-start=\"1907\" data-end=\"1918\">US$ 248<\/strong>, sugerindo um grande potencial de valoriza\u00e7\u00e3o em rela\u00e7\u00e3o aos n\u00edveis atuais.<\/p>\n<p class=\"m-0 p-0 xl:text-pretty body-extra-large overflow-hidden py-3 text-colors-text dark:text-colors-background lg:py-4\">O BofA tamb\u00e9m observa melhorias na\u00a0<strong data-start=\"2031\" data-end=\"2057\">efici\u00eancia operacional<\/strong>\u00a0da Amazon, incluindo a expans\u00e3o das margens no varejo, ganhos de produtividade impulsionados por\u00a0<strong data-start=\"2155\" data-end=\"2167\">rob\u00f3tica<\/strong>\u00a0e economias de custos com a reestrutura\u00e7\u00e3o da gest\u00e3o. Eles veem o neg\u00f3cio de e-commerce da Amazon como resiliente, com uma participa\u00e7\u00e3o dominante de\u00a0<strong data-start=\"2317\" data-end=\"2324\">40%<\/strong>\u00a0do mercado dos Estados Unidos, al\u00e9m de ambi\u00e7\u00f5es internacionais em mercados como\u00a0<strong data-start=\"2405\" data-end=\"2414\">\u00cdndia<\/strong>,\u00a0<strong data-start=\"2416\" data-end=\"2426\">Brasil<\/strong>,\u00a0<strong data-start=\"2428\" data-end=\"2438\">Europa<\/strong>\u00a0e\u00a0<strong data-start=\"2441\" data-end=\"2458\">Oriente M\u00e9dio<\/strong>.<\/p>\n<p class=\"m-0 p-0 xl:text-pretty body-extra-large overflow-hidden py-3 text-colors-text dark:text-colors-background lg:py-4\">Apesar das perspectivas positivas, o BofA reconhece alguns riscos, como o aumento da\u00a0<strong data-start=\"2546\" data-end=\"2562\">concorr\u00eancia<\/strong>\u00a0de empresas como o\u00a0<strong data-start=\"2582\" data-end=\"2593\">Walmart<\/strong>,\u00a0<strong data-start=\"2595\" data-end=\"2618\">riscos regulat\u00f3rios<\/strong>\u00a0e o impacto de\u00a0<strong data-start=\"2634\" data-end=\"2645\">tarifas<\/strong>. No entanto, o banco considera a Amazon uma forte jogada de\u00a0<strong data-start=\"2706\" data-end=\"2733\">intelig\u00eancia artificial<\/strong>\u00a0e espera crescimento est\u00e1vel da receita e expans\u00e3o de margens em rela\u00e7\u00e3o aos concorrentes em 2025.<\/p>\n<p class=\"m-0 p-0 xl:text-pretty body-extra-large overflow-hidden py-3 text-colors-text dark:text-colors-background lg:py-4\">Outros grandes bancos como\u00a0<strong data-start=\"2861\" data-end=\"2869\">Citi<\/strong>,\u00a0<strong data-start=\"2871\" data-end=\"2883\">JPMorgan<\/strong>\u00a0e\u00a0<strong data-start=\"2886\" data-end=\"2904\">Morgan Stanley<\/strong>\u00a0tamb\u00e9m t\u00eam uma vis\u00e3o alinhada com a do BofA, reconhecendo que a Amazon continua a ser uma empresa dominada pela inova\u00e7\u00e3o, com fortes perspectivas de crescimento no longo prazo, centradas no AWS, intelig\u00eancia artificial e e-commerce. A empresa, segundo os analistas, tamb\u00e9m se beneficia de uma execu\u00e7\u00e3o operacional forte e de investimentos estrat\u00e9gicos, embora ainda enfrente desafios em rela\u00e7\u00e3o \u00e0\u00a0<strong data-start=\"3279\" data-end=\"3295\">concorr\u00eancia<\/strong>\u00a0e ao\u00a0<strong data-start=\"3301\" data-end=\"3322\">risco regulat\u00f3rio<\/strong>.<\/p>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A\u00a0Amazon (AMZN)\u00a0est\u00e1 dando passos importantes no desenvolvimento de rob\u00f4s humanoides que t\u00eam o potencial de transformar a entrega de pacotes feitas por humanos, segundo o site\u00a0The Information.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[58,56],"tags":[],"class_list":["post-114915","post","type-post","status-publish","format-standard","hentry","category-amazon","category-l-founders"],"acf":[],"_links":{"self":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts\/114915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=114915"}],"version-history":[{"count":1,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts\/114915\/revisions"}],"predecessor-version":[{"id":114916,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts\/114915\/revisions\/114916"}],"wp:attachment":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=114915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=114915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=114915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}