{"id":114745,"date":"2025-06-02T14:14:22","date_gmt":"2025-06-02T17:14:22","guid":{"rendered":"https:\/\/monitoramento.spmj.com.br\/noticias\/?p=114745"},"modified":"2025-06-02T14:14:22","modified_gmt":"2025-06-02T17:14:22","slug":"carrefour-deixa-a-b3-com-valor-de-mercado-44-menor","status":"publish","type":"post","link":"https:\/\/monitoramento.spmj.com.br\/noticias\/2025\/06\/02\/carrefour-deixa-a-b3-com-valor-de-mercado-44-menor\/","title":{"rendered":"Carrefour deixa a B3 com valor de mercado 44% menor"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/gironews.com\/wp-content\/uploads\/2025\/02\/carrefour-925x400.png\" alt=\"Imagem destaque: Carrefour deixa a B3 com valor de mercado 44% menor\" \/><\/p>\n<div class=\"tema__coluna\">\n<div id=\"weigearx5_1688664288713\" class=\"bloco bloco__tipo-personalizado bloco__col-3\">\n<div class=\"editor-personalizado\">\n<div class=\"bloco__personalizado__item n_texto \">\n<p>No contexto da reorganiza\u00e7\u00e3o societ\u00e1ria para unificar as bases acion\u00e1rias do Carrefour S.A. e da matriz francesa, o Carrefour Brasil saiu da bolsa de valores brasileira no dia 30 de maio, conforme informou a empresa em fato relevante. O papel deixou a B3 com valor de mercado de R$ 17,8 bilh\u00f5es, com a a\u00e7\u00e3o cotada a R$ 8,48 no fechamento da \u00faltima sexta-feira (30), com uma queda de 44% frente ao valor da oferta inicial, de acordo com informa\u00e7\u00f5es do\u00a0<a href=\"https:\/\/www.moneytimes.com.br\/de-ipo-bilionario-a-saida-discreta-carrefour-deixa-b3-com-valor-de-mercado-44-menor-2-igdl\/\" target=\"_blank\" rel=\"noopener\">Money Times<\/a>. Como resultado, as a\u00e7\u00f5es de emiss\u00e3o da companhia passam a ser integralmente detidas pela MergerSub, e os BDRs (Brazilian Depositary Receipts, ou certificados que representam a\u00e7\u00f5es emitidas por empresas em outros pa\u00edses) passam a ser admitidos \u00e0 negocia\u00e7\u00e3o na B3 sob c\u00f3digo \u201cCAFR31\u201d. As eventuais fra\u00e7\u00f5es de BDR decorrentes da implementa\u00e7\u00e3o da transa\u00e7\u00e3o ser\u00e3o agrupadas em n\u00fameros inteiros para, em seguida, serem alienadas no mercado \u00e0 vista administrado pela B3, comenta a empresa.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>No contexto da reorganiza\u00e7\u00e3o societ\u00e1ria para unificar as bases acion\u00e1rias do Carrefour S.A. e da matriz francesa, o Carrefour Brasil saiu da bolsa de valores brasileira no dia 30 de maio, conforme informou a empresa em fato relevante.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[59,56],"tags":[],"class_list":["post-114745","post","type-post","status-publish","format-standard","hentry","category-carrefour","category-l-founders"],"acf":[],"_links":{"self":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts\/114745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=114745"}],"version-history":[{"count":1,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts\/114745\/revisions"}],"predecessor-version":[{"id":114746,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/posts\/114745\/revisions\/114746"}],"wp:attachment":[{"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=114745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=114745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monitoramento.spmj.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=114745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}